{"id":78,"date":"2016-02-20T14:06:00","date_gmt":"2016-02-20T13:06:00","guid":{"rendered":"https:\/\/xeddixx.cluster029.hosting.ovh.net\/?p=78"},"modified":"2026-02-10T11:01:21","modified_gmt":"2026-02-10T10:01:21","slug":"2016-02","status":"publish","type":"post","link":"https:\/\/www.francq.info\/index.php\/blog\/2016-02\/","title":{"rendered":"La gratuit\u00e9 a un co\u00fbt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Internet change profond\u00e9ment notre acc\u00e8s \u00e0 la culture. Arm\u00e9 de quelques mots-cl\u00e9s, on trouve un nombre incalculable de contenus culturels en ligne\u200a<sup data-fn=\"135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6\" class=\"fn\"><a href=\"#135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6\" id=\"135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6-link\">1<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette facilit\u00e9 a progressivement rendu cet acc\u00e8s quasi illimit\u00e9 naturel. L\u00e0 o\u00f9 les premiers internautes \u00e9taient fascin\u00e9s par un contenu culturel accessible d\u2019un simple clic, la masse des usagers aujourd\u2019hui pestent d\u00e8s qu\u2019ils ne trouvent pas rapidement ce qu\u2019ils recherchent. Et pas question de d\u00e9bourser un centime !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout appara\u00eet comme si internet avait fait dispara\u00eetre les co\u00fbts de production, alors qu\u2019il se contente de limiter les co\u00fbts de distribution (ce qui est en soi d\u00e9j\u00e0 r\u00e9volutionnaire). Pourtant, toute cr\u00e9ation de contenu (culturel ou non) implique du travail, surtout quand elle est de qualit\u00e9. La culture du gratuit qui s\u2019est install\u00e9e pose donc la question du financement des contenus culturels de qualit\u00e9.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>La difficile adaptation des m\u00e9dias mat\u00e9riels<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019industrie du disque illustre sans conteste les difficult\u00e9s des acteurs traditionnels. Alors que les revenus atteignaient $ 38 milliards (\u20ac 34,6 milliards) dans les ann\u00e9es 90, ils d\u00e9crurent \u00e0 $ 16,5 milliards (\u20ac 15 milliards) la d\u00e9cennie suivante\u00a0[<a href=\"#1\" rel=\"nofollow\">1<\/a>]. Le piratage, notamment l\u2019utilisation des applications\u00a0<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pair_%C3%A0_pair\" target=\"_blank\" rel=\"noreferrer noopener\">peer-to-peer<\/a><\/em>, contribue en partie \u00e0 ces pertes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le recul des ventes physiques s\u2019explique aussi par d\u2019autres facteurs (diminution de la part des budgets des m\u00e9nages d\u00e9di\u00e9e \u00e0 la culture, fuite de fans devant l\u2019importance prise par le marketing, etc.)\u00a0[<a href=\"#2\" rel=\"nofollow\">2<\/a>,\u00a0<a href=\"#3\" rel=\"nofollow\">3<\/a>]. Certains avancent m\u00eame que les concerts et le\u00a0<a href=\"http:\/\/www.cnrtl.fr\/definition\/merchandising\" target=\"_blank\" rel=\"noreferrer noopener\">merchandising<\/a>\u00a0deviennent la principale source de revenus, les albums \u00e9tant rel\u00e9gu\u00e9s au rang de simples produits d\u2019appel\u00a0[<a href=\"#4\" rel=\"nofollow\">4<\/a>]. C\u2019est sans doute vrai pour les \u00abstars\u00bb, mais pour le reste, les \u00abann\u00e9es dor\u00e9es\u00bb 1970-1990, caract\u00e9ris\u00e9es par une massification des auditeurs, semblent termin\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9tudes men\u00e9es depuis plusieurs ann\u00e9es par le\u00a0<a href=\"http:\/\/www.journalism.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pew Research Center<\/a>\u00a0sur la presse \u00e9crite am\u00e9ricaine montrent que la situation est pire pour ceux qui d\u00e9fendent une presse critique et de qualit\u00e9. Les revenus traditionnels (publicitaires, petites annonces et abonnements) ont non seulement plong\u00e9, mais ils sont loin d\u2019avoir \u00e9t\u00e9 compens\u00e9s par les nouveaux revenus en ligne. En 2008, la presse am\u00e9ricaine licencia 24.000 personnes alors que la fran\u00e7aise fera de m\u00eame pour 2300 personnes en un plus tard\u00a0[<a href=\"#5\" rel=\"nofollow\">5<\/a>].\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et il ne s\u2019agit pas simplement \u00abd\u2019augmenter la productivit\u00e9\u00bb en faisant mieux avec moins, puisqu\u2019on assiste \u00e0 une pr\u00e9carisation des journalistes par l\u2019utilisation accrue de&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Pigiste\" rel=\"noreferrer noopener\">pigistes<\/a>. Les \u00e9tudes mettent aussi en \u00e9vidence une diminution des correspondants \u00e9trangers et une moindre couverture des \u00e9v\u00e9nements internationaux. Voil\u00e0 qui encouragera certainement le renforcement du repli sur soi actuel dans nos d\u00e9mocraties occidentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Montr\u00e9s du doigt, les fournisseurs de services en ligne<sup data-fn=\"0387ea8b-9e30-4f81-8934-36e0a26e7d6a\" class=\"fn\"><a href=\"#0387ea8b-9e30-4f81-8934-36e0a26e7d6a\" id=\"0387ea8b-9e30-4f81-8934-36e0a26e7d6a-link\">2<\/a><\/sup> r\u00e9torquent que les acteurs traditionnels d\u00e9fendent leurs rentes et ne se montrent pas assez inventifs pour exploiter intelligemment internet et d\u00e9velopper des mod\u00e8les \u00e9conomiques innovants. Pour le dire autrement, internet n\u2019affecterait en rien la valeur ajout\u00e9e structurelle des contenus culturels en ligne. Il offrirait au contraire des opportunit\u00e9s nouvelles pour la capter.<em>&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Spotify\" target=\"_blank\" rel=\"noreferrer noopener\">Spotify<\/a><\/em>&nbsp;affirme ainsi avoir vers\u00e9&nbsp;<a href=\"https:\/\/press.spotify.com\/be-fr\/about\/\" target=\"_blank\" rel=\"noreferrer noopener\">$ 3 milliards (\u20ac 2.7 milliards) en droits d&rsquo;auteurs<\/a>\u200a<sup data-fn=\"b16bdef4-3c7b-455f-8624-88edbc8ab153\" class=\"fn\"><a href=\"#b16bdef4-3c7b-455f-8624-88edbc8ab153\" id=\"b16bdef4-3c7b-455f-8624-88edbc8ab153-link\">3<\/a><\/sup>&nbsp;depuis sa cr\u00e9ation.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Une accessibilit\u00e9 des contenus culturels accrue<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">On ne peut nier qu\u2019internet contribue \u00e0 une plus grande accessibilit\u00e9 des contenus culturels. Quoi de plus embl\u00e9matique que le tube plan\u00e9taire \u00ab<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Gangnam_Style\" rel=\"noreferrer noopener\">Gangnam Style<\/a>\u00bb du chanteur sud-cor\u00e9en&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Psy_%28chanteur%29\" rel=\"noreferrer noopener\">Psy<\/a>&nbsp;vu plus de deux milliards de fois sur&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/YouTube\" rel=\"noreferrer noopener\">YouTube<\/a>&nbsp;? La force d\u2019internet r\u00e9side en fait dans la multiplication des canaux reliant publics et contenus culturels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En commen\u00e7ant par les canaux de distribution : longtemps, une visite physique (disquaires, librairies, cin\u00e9mas, mus\u00e9es, etc.) \u00e9tait le passage oblig\u00e9 pour consommer<sup data-fn=\"f138d4d2-a081-49da-98d0-631a5a40712f\" class=\"fn\"><a href=\"#f138d4d2-a081-49da-98d0-631a5a40712f\" id=\"f138d4d2-a081-49da-98d0-631a5a40712f-link\">4<\/a><\/sup> des contenus culturels. Aujourd\u2019hui, entre les plates-formes de diffusion en continu et\/ou d\u2019achats en ligne ainsi que les diverses visites immat\u00e9rielles, les canaux de distribution explosent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame, les canaux de communication foisonnent. La pr\u00e9sence sur internet, et singuli\u00e8rement sur les r\u00e9seaux sociaux en ligne, am\u00e9liore la visibilit\u00e9 des cr\u00e9ateurs et facilite les contacts, plus ou moins directs, avec leurs publics. Le cas des&nbsp;Arctic Monkeys, m\u00eame s\u2019il reste l\u2019exception, est souvent cit\u00e9 pour illustrer comment une mobilisation en ligne par des fans peut mener \u00e0 faire conna\u00eetre des artistes au grand public.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet voit \u00e9galement la prolif\u00e9ration des canaux de m\u00e9diation. De fait, c\u2019en est fini d\u2019une m\u00e9diation r\u00e9serv\u00e9e \u00e0 quelques acteurs seulement (disquaires, critiques \u00abtraditionnels\u00bb, etc.). Non seulement, n\u2019importe qui peut participer \u00e0 la m\u00e9diation d\u2019un contenu culturel \u2013 par exemple \u00e0 travers son&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Blog\" rel=\"noreferrer noopener\">blog<\/a>, sa page&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Facebook\" rel=\"noreferrer noopener\">Facebook<\/a><\/em>&nbsp;et\/ou son compte&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Twitter\" rel=\"noreferrer noopener\">Twitter<\/a><\/em>&nbsp;\u2013 mais les algorithmes (classement, suggestions, etc.) occupent une place toujours plus centrale dans nos habitudes de consommation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cela s\u2019ajoute une cr\u00e9ation de contenus culturels parfois facilit\u00e9e par l\u2019informatique. Ainsi, de nos jours, un \u00absimple\u00bb ordinateur et quelques logiciels suffisent pour composer un morceau de musique et l\u2019enregistrer dans son salon. Ensuite, internet en permet la diffusion hors des fili\u00e8res \u00abtraditionnelles\u00bb.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>La r\u00e9alit\u00e9 des revenus des cr\u00e9ateurs<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019il est indiscutable que certains cr\u00e9ateurs s\u2019en sortent tr\u00e8s bien, ce n\u2019est pas forc\u00e9ment le cas pour tous. D\u2019abord parce que certains canaux de distribution, notamment les plates-formes de t\u00e9l\u00e9chargement ill\u00e9gal, ne reversent rien aux ayants droit des contenus culturels distribu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis que le piratage des bandes dessin\u00e9es se d\u00e9veloppe (celles-ci sont d\u2019abord scann\u00e9es puis mises en ligne), certains auteurs voient, par exemple, leurs revenus baisser de 30%. Concr\u00e8tement, plusieurs auteurs (et \u00e9diteurs) n\u2019osent plus monter des projets ambitieux de peur de perdre de l\u2019argent. Or, avec l\u2019av\u00e8nement du multim\u00e9dia, de nombreux projets innovants demandent des investissements non n\u00e9gligeables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais les plates-formes de diffusion l\u00e9gale posent \u00e9galement question, comme le montrent celles sp\u00e9cialis\u00e9es dans la musique. Elles r\u00e9mun\u00e8rent les ayants droit aux alentours des 0,17 centimes d\u2019euro par \u00e9coute&nbsp;[<a href=\"#7\">7<\/a>]. Certes, une chanson \u00e9cout\u00e9e cent millions de fois pas an (par exemple 2 millions internautes qui l\u2019\u00e9coutent 5 fois par mois) g\u00e9n\u00e8re un tr\u00e8s confortable revenu de 170.000 \u20ac\/an. Mais combien de chansons sont concern\u00e9es ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plupart des plates-formes proposent en effet aujourd\u2019hui un catalogue gigantesque pour un faible montant forfaitaire (typiquement 10 ou 20 \u20ac par mois). Si le consommateur a tout \u00e0 y gagner, chaque contenu culturel individuel (chanson, film, etc.) se trouve un peu plus noy\u00e9 dans une masse. Les probabilit\u00e9s d\u2019\u00e9coutes multiples, v\u00e9ritables sources de revenus en ligne, s\u2019amenuisent donc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9alit\u00e9, internet impose son mod\u00e8le \u00e9conomique, dans lequel les revenus sont principalement bas\u00e9s sur des volumes de ventes, aux contenus culturels. Le cas du syst\u00e8me de publicit\u00e9 en ligne&nbsp;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/AdWords\" target=\"_blank\" rel=\"noreferrer noopener\">Google AdWords<\/a><\/em> est illustratif. Chaque annonceur ne paye que quelques centimes d\u2019euro par clic vers sa page Web,&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>&nbsp;se r\u00e9mun\u00e9rant sur la masse totale des clics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais est-ce un mod\u00e8le adapt\u00e9 pour encourager les cr\u00e9ateurs \u00e0 produire des contenus culturels de qualit\u00e9 ? Ont-ils encore de r\u00e9elles marges de man\u0153uvre pour n\u00e9gocier leurs talents ? Ces questions m\u00e9ritent d\u2019\u00eatre pos\u00e9es.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>La captation des acteurs du num\u00e9rique<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">En fait, on assiste \u00e0 un glissement dans la cha\u00eene de valorisation des contenus culturels lorsqu\u2019ils passent par les canaux du num\u00e9rique. D\u00e9sormais, les applications et les infrastructures prennent le pas sur les contenus culturels en ligne. Pour le dire autrement, les ing\u00e9nieurs et informaticiens apparaissent parfois comme plus importants que les cr\u00e9ateurs de contenus culturels !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour certains, la r\u00e9volution du num\u00e9rique est d\u2019avoir quasi aboli le co\u00fbt de stockage des contenus culturels en ligne par rapport \u00e0 celui physique dans les rayons, ce qui permet d\u2019accro\u00eetre la diversit\u00e9 de l\u2019offre\u00a0[<a href=\"#8\" rel=\"nofollow\">8<\/a>]. C\u2019est \u00e9videmment vrai. Pour autant, avec la multiplication des contenus culturels disponibles sur une m\u00eame plate-forme et la diffusion rendue possible partout et sur diff\u00e9rents supports (ordinateurs, smartphones, etc.), les co\u00fbts d\u2019infrastructures et de logistique explosent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cela s\u2019ajoutent les co\u00fbts de d\u00e9veloppement des algorithmes qui jouent un r\u00f4le fondamental dans les plates-formes en ligne. Leur croissance est en effet en partie li\u00e9e aux algorithmes de profilage et de recommandations qui am\u00e8nent leurs clients \u00e0 consommer plus. Et ces plates-formes ajoutent sans cesse de nouvelles fonctionnalit\u00e9s connexes (biographies, \u00e9valuations en ligne, r\u00e9servations de billets, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces d\u00e9veloppements informatiques nouveaux sont souvent une question de survie. Bas\u00e9s sur des m\u00e9thodes complexes d\u2019<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Apprentissage_automatique\" rel=\"noreferrer noopener\">apprentissage automatique<\/a>, ils n\u00e9cessitent le recrutement continu de profils extr\u00eamement pointus. La partie technique demande donc des investissements toujours plus importants, sans que cela apporte r\u00e9ellement quelque chose du point de vue artistique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne faut d\u2019ailleurs pas s\u2019inqui\u00e9ter pour les entreprises num\u00e9riques actives dans ce domaine puisqu\u2019elles voient leur valeur exploser. En 2014,\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Apple\" target=\"_blank\" rel=\"noreferrer noopener\">Apple<\/a>\u00a0rach\u00e8te\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Beats_Electronics\" target=\"_blank\" rel=\"noreferrer noopener\">Beats Electronics<\/a>, qui propose un service de lecture en continu de musique, pour $ 3 milliards (\u20ac 2,2 milliards)\u00a0[<a href=\"#6\" rel=\"nofollow\">6<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame,\u00a0<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Spotify\" target=\"_blank\" rel=\"noreferrer noopener\">Spotify<\/a><\/em>\u00a0r\u00e9ussit en 2015 une lev\u00e9e de fonds de $ 400 millions (\u20ac 364 millions), ce qui repr\u00e9sente une valorisation globale de $ 8 milliards (\u20ac 7,2 milliards)\u00a0[<a href=\"#6\" rel=\"nofollow\">6<\/a>]. Rapport\u00e9e au total de\u00a0<a href=\"https:\/\/press.spotify.com\/be-fr\/about\/\" target=\"_blank\" rel=\"noreferrer noopener\">$ 3 milliards (\u20ac 2.7 milliards) vers\u00e9s en droits d&rsquo;auteurs<\/a>\u200a<sup data-fn=\"170f6e60-fbca-46d5-b756-8f2cde70efa9\" class=\"fn\"><a href=\"#170f6e60-fbca-46d5-b756-8f2cde70efa9\" id=\"170f6e60-fbca-46d5-b756-8f2cde70efa9-link\">5<\/a><\/sup>, cela signifie que la partie technique \u00abvaut\u00bb quasi 3 fois plus que les contenus culturels diffus\u00e9s !<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>La baisse tendancielle de la valeur \u00e0 l\u2019unit\u00e9 des contenus culturels en ligne<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Sachant que les d\u00e9penses en mati\u00e8re de contenus culturels tendent \u00e0 ne pas augmenter (voire \u00e0 diminuer)\u00a0[<a href=\"#3\" rel=\"nofollow\">3<\/a>], les acteurs du num\u00e9rique captent une part toujours plus importante de celles-ci au d\u00e9triment de la production de contenus culturels proprement dite. De plus, quelques acteurs sont devenus \u00e0 ce point incontournables qu\u2019ils constituent un\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Oligopole\" target=\"_blank\" rel=\"noreferrer noopener\">oligopole<\/a>\u00a0de fait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certains imposent ainsi les prix de vente des contenus culturels sur leurs plates-formes, typiquement 9,99 \u20ac pour un livre ou 0,99 \u20ac pour une chanson. En imposant des prix plancher \u00e0 l\u2019unit\u00e9, ils cherchent bien \u00e9videmment \u00e0 augmenter leur volume de ventes global. Mais ils mettent aussi tous les contenus culturels sur le m\u00eame pied, et cela qu\u2019ils soient de niche ou qu\u2019ils visent un public plus large.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le diff\u00e9rend entre les journaux belges francophones et le service\u00a0<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google_Actualit%C3%A9s\" target=\"_blank\" rel=\"noreferrer noopener\">Google News<\/a><\/em>\u00a0est particuli\u00e8rement exemplatif. Ce dernier reprenait des contenus des premiers sans les r\u00e9mun\u00e9rer tout en g\u00e9n\u00e9rant des revenus via ses publicit\u00e9s en ligne. Apr\u00e8s avoir gagn\u00e9 leur proc\u00e8s en 2006, les journaux sont parvenus \u00e0 un accord avec\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>\u00a0en 2012. N\u00e9anmoins, on peut se demander si les journaux s\u2019y retrouvent r\u00e9ellement ou si la puissance de<em>\u00a0<\/em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>\u00a0les a oblig\u00e9s \u00e0 n\u00e9gocier. Il faut dire que, depuis 2011,\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>\u00a0ne r\u00e9f\u00e9ren\u00e7ait plus du tout ces journaux\u00a0[<a href=\"#9\" rel=\"nofollow\">9<\/a>]\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre les faibles forfaits demand\u00e9s pour acc\u00e9der \u00e0 un catalogue quasi illimit\u00e9, les co\u00fbts engendr\u00e9s par la technique et les revenus des ayants droit grignot\u00e9s par des acteurs sur-puissants, les contenus culturels voient leur valeur (d\u2019\u00e9change) diminuer sans cesse d\u00e8s lors qu\u2019ils sont m\u00e9diatisables par internet. Pire, la plupart des ayants droit, notamment les producteurs de contenus culturels, ne g\u00e9n\u00e8rent pas l\u2019effet de masse suffisant pour compenser cette diminution \u00e0 l\u2019unit\u00e9.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Le financement de la production de contenus culturels<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Comme beaucoup, je d\u00e9fends un acc\u00e8s le plus libre et le plus large possible \u00e0 la culture pour tous. Les contenus culturels sont sans doute ce qui caract\u00e9rise r\u00e9ellement&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Homo_sapiens\" rel=\"noreferrer noopener\">Homo Sapiens<\/a><\/em>. Ce n\u2019est pas un hasard si les sp\u00e9cialistes de la pr\u00e9histoire utilisent les artefacts culturels produits par nos anc\u00eatres (peintures murales, bijoux, etc.) pour comprendre nos origines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour autant, dans le syst\u00e8me capitaliste actuel, les contenus culturels sont \u00e9galement des marchandises. En effet, m\u00eame si certains pays subventionnent de la cr\u00e9ation de contenus culturels, c\u2019est souvent avec parcimonie, et tous ne le font pas. Nous savons depuis\u00a0Aristote\u00a0que toute marchandise poss\u00e8de non seulement une \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Valeur_d'usage\" target=\"_blank\" rel=\"noreferrer noopener\">valeur d&rsquo;usage<\/a>\u00bb, mais \u00e9galement une\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Valeur_d'%C3%A9change\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abvaleur d&rsquo;\u00e9change<\/a>\u00bb (son \u00abprix\u00bb)\u00a0[<a href=\"#10\" rel=\"nofollow\">10<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis le XVIII<sup>\u00e8me<\/sup>\u00a0si\u00e8cle, les \u00e9conomistes ont \u00e9tabli que c\u2019est le travail accumul\u00e9 pour produire des marchandises qui fixe les rapports entre leur valeur d\u2019\u00e9change. Un des apports de\u00a0Karl Marx\u00a0est d\u2019avoir compris que ce travail \u00e9tait un \u00abtravail g\u00e9n\u00e9ral abstrait\u00bb\u00a0[<a href=\"#11\" rel=\"nofollow\">11<\/a>]. Pour le dire autrement, la valeur d\u2019\u00e9change d\u2019une marchandise est fix\u00e9e par le nombre d\u2019heures n\u00e9cessaires en moyenne pour la produire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appliquons cela aux contenus culturels. La valeur d\u2019\u00e9change d\u2019un contenu culturel correspond au temps qu\u2019un \u00abartiste moyen\u00bb mettrait pour le cr\u00e9er. Autrement dit, en baissant la valeur d\u2019\u00e9change d\u2019un contenu culturel, on diminue le temps qu\u2019un \u00abartiste moyen\u00bb consacre \u00e0 sa cr\u00e9ation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Or, \u00e0 part quelques exceptions qui marquent l\u2019histoire artistique, produire un contenu culturel de qualit\u00e9 demande du temps. Je ne parle m\u00eame pas ici des \u00e9ventuelles ressources suppl\u00e9mentaires n\u00e9cessaires<sup data-fn=\"7fb7722a-b7ea-4a8a-b757-02a75517f252\" class=\"fn\"><a href=\"#7fb7722a-b7ea-4a8a-b757-02a75517f252\" id=\"7fb7722a-b7ea-4a8a-b757-02a75517f252-link\">6<\/a><\/sup> (mat\u00e9riels, techniciens sp\u00e9cialis\u00e9s, etc.). D\u00e8s lors, la diminution structurelle de la valeur d\u2019\u00e9change des contenus culturels en ligne risque fort bien d\u2019impacter leur qualit\u00e9. La presse \u00e9crite en est, malheureusement, la meilleure illustration.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Quelle cha\u00eene de valeur pour les contenus culturels en ligne ?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Qu\u2019on me comprenne bien, je n\u2019attaque pas l\u2019id\u00e9e qu\u2019internet doit permettre un acc\u00e8s \u00e0 la culture \u00e0 tous et \u00e0 moindre co\u00fbt, voire gratuitement. Je me demande simplement si la mani\u00e8re dont les choses sont structur\u00e9es aujourd\u2019hui est le meilleur chemin pour y arriver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma crainte est qu\u2019en rognant sur les revenus des cr\u00e9ateurs, par le piratage ou par des mod\u00e8les \u00e9conomiques issus d\u2019un num\u00e9rique peu avantageux pour eux, on finisse par d\u00e9truire une certaine diversit\u00e9 puisque seuls les contenus culturels en ligne capables de g\u00e9n\u00e9rer un effet de masse sont rentables. Mais je n\u2019ai pas de solution miracle\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une plus grande prise de conscience du \u00abgrand public\u00bb quant aux enjeux li\u00e9s \u00e0 la production de contenus culturels m\u2019appara\u00eet d\u00e8s lors indispensable. Je reste en effet convaincu que des d\u00e9marches individuelles peuvent infl\u00e9chir la tendance actuelle. Sans rejeter l\u2019utilisation des grandes plates-formes, chacun pourrait combiner celle-ci avec des habitudes de consommation plus \u00e9quitables pour les cr\u00e9ateurs, par exemple en maintenant un certain budget d\u2019achats et en passant aussi par d\u2019autres canaux de distribution.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il serait sans doute \u00e9galement pertinent de renforcer \u00abl\u2019\u00e9ducation artistique\u00bb des citoyens pour mieux les sensibiliser. Diff\u00e9rentes initiatives visant \u00e0 mettre en relation contenus culturels et publics existent et doivent \u00eatre encourag\u00e9es. Je pense aussi que la r\u00e9introduction de cours dans les \u00e9coles (musique, dessin, th\u00e9\u00e2tre, etc.), en collaboration avec des professionnels, serait importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une autre piste possible serait de taxer davantage les activit\u00e9s en ligne m\u00e9diatisant des contenus culturels pour augmenter ensuite les subventions accord\u00e9es pour la cr\u00e9ation. Cela demanderait \u00e9videmment d\u2019apporter une r\u00e9ponse satisfaisante \u00e0 la question de l\u2019affectation de ces nouveaux subsides (qui ? comment ? combien ?). Mais surtout, cela pose le probl\u00e8me des multinationales d\u00e9tentrices des plates-formes les plus populaires, qui \u00e9ludent en grande partie les imp\u00f4ts dans les diff\u00e9rents pays o\u00f9 elles exercent\u00a0[<a href=\"#12\" rel=\"nofollow\">12<\/a>]. Mais ceci est une autre histoire\u2026<a href=\"http:\/\/www.twitter.com\/pascalfrancq\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">R\u00e9f\u00e9rences<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"1\">[1]&nbsp;Eric Pfanner, \u00ab<a href=\"http:\/\/www.nytimes.com\/2013\/02\/27\/technology\/music-industry-records-first-revenue-increase-since-1999.html\" target=\"_blank\" rel=\"noreferrer noopener\">Music Industry Reports a Rise in Sales, Crediting Digital<\/a>\u00bb,&nbsp;<em>The New York Times<\/em>, 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"2\">[2]&nbsp;Mark Fox, \u00abe-Commerce Business Models for the Music Industry\u00bb,&nbsp;<em>Popular Music and Society<\/em>, 27(2), pp. 201\u2013220, 2004.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"3\">[3]&nbsp;Martin Peitz&nbsp;&amp;&nbsp;Patrick Waelbroeck, \u00abAn Economist\u2019s Guide to Digital Music\u00bb,&nbsp;<em>Economic Studies<\/em>, 51(2\u20133), pp. 359\u2013428, 2005.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"4\">[4]&nbsp;Fred Goodman, \u00ab<a href=\"http:\/\/www.rollingstone.com\/news\/story\/20830491\/rocks_new_economy_making_money_when_cds_dont_sell.\" target=\"_blank\" rel=\"noreferrer noopener\">Rock\u2019s New Economy: Making Money When CDs Don\u2019t Sell<\/a>\u00bb,&nbsp;<em>Rolling Stone<\/em>, 2008.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"5\">[5]&nbsp;Marie B\u00e9nilde, \u00abQui veut encore financer la presse\u202f?\u00bb,&nbsp;<em>Le Monde diplomatique<\/em>, 57(671), p. 7, 2010.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"6\">[6]&nbsp;Ben Sisario, \u00ab<a href=\"http:\/\/www.nytimes.com\/2015\/05\/09\/business\/media\/as-spotify-expands-revenue-rises-and-losses-deepen.html\" target=\"_blank\" rel=\"noreferrer noopener\">Media Spotify\u2019s Revenue Is Growing, but So Are Its Losses<\/a>\u00bb,&nbsp;<em>New York Times<\/em>, 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"7\">[7]&nbsp;Pierre Breteau, \u00ab<a href=\"http:\/\/www.lemonde.fr\/les-decodeurs\/article\/2015\/06\/25\/streaming-musical-combien-touchent-les-artistes_4662105_4355770.html\" target=\"_blank\" rel=\"noreferrer noopener\">Streaming \u00bb musical : combien touchent les artistes ?<\/a>\u00bb,&nbsp;<em>Le Monde<\/em>, 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"8\">[8]&nbsp;Chris Anderson,&nbsp;<em>The Long Tail: Why the Future of Business is Selling Less of More<\/em>, 2e \u00e9d., Hyperion, 2008.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"9\">[9]&nbsp;Philippe Laloux, \u00ab<a href=\"http:\/\/www.lesoir.be\/archives?url=\/debats\/editos\/2011-07-16\/google-bafoue-la-neutralite-du-net-851379.php\" target=\"_blank\" rel=\"noreferrer noopener\">Google bafoue la neutralit\u00e9 du Net<\/a>\u00bb,&nbsp;<em>Le Soir<\/em>, 16 juillet 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"10\">[10]&nbsp;Aristote, \u00abLa politique\u00bb dans&nbsp;<em>\u0152uvres<\/em>, Gallimard, Pl\u00e9iade, 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"11\">[11]&nbsp;Karl Marx, \u00abCapital Livre 1\u00bb dans&nbsp;<em>\u0152uvres&nbsp;<\/em>\u2013<em>&nbsp;\u00c9conomie I<\/em>, Gallimard, Pl\u00e9iade, 1963.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"12\">[12]&nbsp;Organisation for Economic Co-operation and Development, \u00ab<em><a href=\"http:\/\/www.oecd-ilibrary.org\/content\/book\/9789264192904-fr.\" target=\"_blank\" rel=\"noreferrer noopener\">Lutter contre l\u2019\u00e9rosion de la base d\u2019imposition et le transfert de b\u00e9n\u00e9fices<\/a><\/em>\u00bb, rapport, 2013.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Notes<\/h5>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6\">La cat\u00e9gorie plus g\u00e9n\u00e9rale de \u00abcontenus en ligne\u00bb comprend en plus les applications en ligne fournissant des services, dont certaines sont des m\u00e9diateurs de contenus culturels. Ainsi, un site de lecture en continu de musique (application en ligne) permet aux internautes d\u2019\u00e9couter des chansons (contenus culturels). Dans une premi\u00e8re version de ce billet, j\u2019avais utilis\u00e9 l\u2019expression \u00ab<a href=\"http:\/\/opinions.otlet-institute.org\/2016-01.html\" target=\"_blank\" rel=\"noreferrer noopener\">contenus synth\u00e9tiques<\/a>\u00a0symboliques\u00bb. Mais apr\u00e8s plusieurs remarques, je me suis rendu compte que celle-ci compliquait la lecture. J\u2019ai donc privil\u00e9gi\u00e9 une expression plus usuelle.\u00a0(journaux, livres, musique et films) en suivant l\u2019un ou l\u2019autre hyperlien propos\u00e9, le tout g\u00e9n\u00e9ralement sans payer. <a href=\"#135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6-link\" aria-label=\"Aller \u00e0 la note de bas de page 1\">\u21a9\ufe0e<\/a><\/li><li id=\"0387ea8b-9e30-4f81-8934-36e0a26e7d6a\">Les fournisseurs d\u2019acc\u00e8s, en proposant des d\u00e9bits disponibles de plus en plus importants \u00e0 des prix toujours plus bas, contribuent \u00e9videmment \u00e0 l\u2019envie de consommation en ligne des internautes. En pratique, il suffit aujourd\u2019hui souvent de quelques heures pour t\u00e9l\u00e9charger un film ou une saison enti\u00e8re d\u2019une s\u00e9rie t\u00e9l\u00e9vis\u00e9e. <a href=\"#0387ea8b-9e30-4f81-8934-36e0a26e7d6a-link\" aria-label=\"Aller \u00e0 la note de bas de page 2\">\u21a9\ufe0e<\/a><\/li><li id=\"b16bdef4-3c7b-455f-8624-88edbc8ab153\">Site Web officiel consult\u00e9 le 24 f\u00e9vrier 2016. <a href=\"#b16bdef4-3c7b-455f-8624-88edbc8ab153-link\" aria-label=\"Aller \u00e0 la note de bas de page 3\">\u21a9\ufe0e<\/a><\/li><li id=\"f138d4d2-a081-49da-98d0-631a5a40712f\">\u00abConsommer\u00bb doit \u00eatre pris ici dans son sens le plus neutre, et non comme l\u2019expression d\u2019une quelconque forme de marchandisation des contenus culturels (sur laquelle je reviens plus loin dans ce billet). <a href=\"#f138d4d2-a081-49da-98d0-631a5a40712f-link\" aria-label=\"Aller \u00e0 la note de bas de page 4\">\u21a9\ufe0e<\/a><\/li><li id=\"170f6e60-fbca-46d5-b756-8f2cde70efa9\">Site Web officiel consult\u00e9 le 24 f\u00e9vrier 2016. <a href=\"#170f6e60-fbca-46d5-b756-8f2cde70efa9-link\" aria-label=\"Aller \u00e0 la note de bas de page 5\">\u21a9\ufe0e<\/a><\/li><li id=\"7fb7722a-b7ea-4a8a-b757-02a75517f252\">Les valeurs d\u2019\u00e9change de toutes ces ressources sont \u00e9galement li\u00e9es \u00e0 un travail g\u00e9n\u00e9ral abstrait. Par exemple, le prix d\u2019\u00e9change d\u2019un musicien (sa \u00abr\u00e9mun\u00e9ration\u00bb) correspond au temps moyen n\u00e9cessaire pour acqu\u00e9rir sa ma\u00eetrise artistique. En d\u2019autres termes, en engageant des musiciens \u00abmoins chers\u00bb, on engage des personnes qui ont consacr\u00e9 moins de temps \u00e0 la ma\u00eetrise de leur(s) instrument(s). <a href=\"#7fb7722a-b7ea-4a8a-b757-02a75517f252-link\" aria-label=\"Aller \u00e0 la note de bas de page 6\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Internet change profond\u00e9ment notre acc\u00e8s \u00e0 la culture. Arm\u00e9 de quelques mots-cl\u00e9s, on trouve un nombre incalculable de contenus culturels en ligne\u200a. Cette facilit\u00e9 a progressivement rendu cet acc\u00e8s quasi illimit\u00e9 naturel. L\u00e0 o\u00f9 les premiers internautes \u00e9taient fascin\u00e9s par un contenu culturel accessible d\u2019un simple clic, la masse des usagers aujourd\u2019hui pestent d\u00e8s qu\u2019ils [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"[{\"content\":\"La cat\u00e9gorie plus g\u00e9n\u00e9rale de \u00abcontenus en ligne\u00bb comprend en plus les applications en ligne fournissant des services, dont certaines sont des m\u00e9diateurs de contenus culturels. Ainsi, un site de lecture en continu de musique (application en ligne) permet aux internautes d\u2019\u00e9couter des chansons (contenus culturels). Dans une premi\u00e8re version de ce billet, j\u2019avais utilis\u00e9 l\u2019expression \u00ab<a href=\\\"http:\/\/opinions.otlet-institute.org\/2016-01.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">contenus synth\u00e9tiques<\/a>\u00a0symboliques\u00bb. Mais apr\u00e8s plusieurs remarques, je me suis rendu compte que celle-ci compliquait la lecture. J\u2019ai donc privil\u00e9gi\u00e9 une expression plus usuelle.\u00a0(journaux, livres, musique et films) en suivant l\u2019un ou l\u2019autre hyperlien propos\u00e9, le tout g\u00e9n\u00e9ralement sans payer.\",\"id\":\"135f6dbf-f9b3-46e0-a18a-8ad1820f8ec6\"},{\"content\":\"Les fournisseurs d\u2019acc\u00e8s, en proposant des d\u00e9bits disponibles de plus en plus importants \u00e0 des prix toujours plus bas, contribuent \u00e9videmment \u00e0 l\u2019envie de consommation en ligne des internautes. En pratique, il suffit aujourd\u2019hui souvent de quelques heures pour t\u00e9l\u00e9charger un film ou une saison enti\u00e8re d\u2019une s\u00e9rie t\u00e9l\u00e9vis\u00e9e.\",\"id\":\"0387ea8b-9e30-4f81-8934-36e0a26e7d6a\"},{\"content\":\"Site Web officiel consult\u00e9 le 24 f\u00e9vrier 2016.\",\"id\":\"b16bdef4-3c7b-455f-8624-88edbc8ab153\"},{\"content\":\"\u00abConsommer\u00bb doit \u00eatre pris ici dans son sens le plus neutre, et non comme l\u2019expression d\u2019une quelconque forme de marchandisation des contenus culturels (sur laquelle je reviens plus loin dans ce billet).\",\"id\":\"f138d4d2-a081-49da-98d0-631a5a40712f\"},{\"content\":\"Site Web officiel consult\u00e9 le 24 f\u00e9vrier 2016.\",\"id\":\"170f6e60-fbca-46d5-b756-8f2cde70efa9\"},{\"content\":\"Les valeurs d\u2019\u00e9change de toutes ces ressources sont \u00e9galement li\u00e9es \u00e0 un travail g\u00e9n\u00e9ral abstrait. Par exemple, le prix d\u2019\u00e9change d\u2019un musicien (sa \u00abr\u00e9mun\u00e9ration\u00bb) correspond au temps moyen n\u00e9cessaire pour acqu\u00e9rir sa ma\u00eetrise artistique. En d\u2019autres termes, en engageant des musiciens \u00abmoins chers\u00bb, on engage des personnes qui ont consacr\u00e9 moins de temps \u00e0 la ma\u00eetrise de leur(s) instrument(s).\",\"id\":\"7fb7722a-b7ea-4a8a-b757-02a75517f252\"}]"},"categories":[104],"tags":[96,98],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","category-economy","tag-economy","tag-politic"],"views":14,"_links":{"self":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":7,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"predecessor-version":[{"id":1971,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/78\/revisions\/1971"}],"wp:attachment":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}