{"id":3521,"date":"2026-05-20T08:28:29","date_gmt":"2026-05-20T06:28:29","guid":{"rendered":"https:\/\/www.francq.info\/?p=3521"},"modified":"2026-06-14T11:22:41","modified_gmt":"2026-06-14T09:22:41","slug":"2026-05","status":"publish","type":"post","link":"https:\/\/www.francq.info\/index.php\/blog\/2026-05\/","title":{"rendered":"La guerre de l&rsquo;IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fin avril 2026, la revue en ligne <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Grand_Continent\" target=\"_blank\" rel=\"noreferrer noopener\">Le Grand Continent<\/a><\/em> traduit et commente une note interne du principal conseiller scientifique du pr\u00e9sident am\u00e9ricain sur l&rsquo;intelligence artificielle (IA) [<a href=\"#1\" rel=\"nofollow\">1<\/a>]. Le document d\u00e9nonce un piratage des mod\u00e8les am\u00e9ricains par la Chine et appelle \u00e0 des mesures de r\u00e9torsion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la guerre g\u00e9ostrat\u00e9gique qui oppose les g\u00e9ants chinois et \u00e9tasunien, l&rsquo;IA joue un r\u00f4le pivot. Cette opposition ne date pas d&rsquo;hier puisque d\u00e8s la premi\u00e8re pr\u00e9sidence de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Donald_Trump\" target=\"_blank\" rel=\"noreferrer noopener\">Donald Trump<\/a>, les \u00c9tats-Unis freinent l&rsquo;acc\u00e8s de la Chine \u00e0 certains composants essentiels de l&rsquo;IA. Cette politique s&rsquo;est poursuivie sous le mandat de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Joe_Biden\" target=\"_blank\" rel=\"noopener\">Joe Biden<\/a> et perdure partiellement aujourd&rsquo;hui<sup data-fn=\"c8134819-4d19-4502-bf72-fd51380dc692\" class=\"fn\"><a href=\"#c8134819-4d19-4502-bf72-fd51380dc692\" id=\"c8134819-4d19-4502-bf72-fd51380dc692-link\">1<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;impact de l&rsquo;IA sur nos soci\u00e9t\u00e9s semble tellement colossal<sup data-fn=\"4ed391cf-4520-4c2c-ae83-af4fdb829831\" class=\"fn\"><a href=\"#4ed391cf-4520-4c2c-ae83-af4fdb829831\" id=\"4ed391cf-4520-4c2c-ae83-af4fdb829831-link\">2<\/a><\/sup> que d&rsquo;autres acteurs tentent d&rsquo;occuper une place de choix dans l&rsquo;\u00e9cosyst\u00e8me de l&rsquo;IA ou, \u00e0 d\u00e9faut, d&rsquo;acqu\u00e9rir au moins une certaine autonomie strat\u00e9gique. L&rsquo;Union europ\u00e9enne appara\u00eet, \u00e0 l&rsquo;instar d&rsquo;autres secteurs industriels, comme disposant d&rsquo;un fort potentiel mais d&rsquo;une incapacit\u00e9 chronique \u00e0 construire des politiques \u00e0 la hauteur des enjeux.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Les \u00c9tats-Unis, berceau de l&rsquo;IA<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;histoire est d\u00e9sormais connue. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Conf\u00e9rence_de_Dartmouth\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c0 l&rsquo;\u00e9t\u00e9 1956 \u00e0 Dartmouth<\/a> des universitaires am\u00e9ricains \u00abfondent\u00bb une nouvelle discipline qui deviendra l&rsquo;IA<sup data-fn=\"7b5c8010-dc7a-48e6-a1ba-a58e518e0153\" class=\"fn\"><a href=\"#7b5c8010-dc7a-48e6-a1ba-a58e518e0153\" id=\"7b5c8010-dc7a-48e6-a1ba-a58e518e0153-link\">3<\/a><\/sup>. L&rsquo;informatique est encore naissante et son \u00e9volution fulgurante difficilement pr\u00e9visible, la cr\u00e9ation du premier <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Circuit_int\u00e9gr\u00e9\" target=\"_blank\" rel=\"noreferrer noopener\">circuit int\u00e9gr\u00e9<\/a> arrivant quelques ann\u00e9es plus tard. Mais, malgr\u00e9 les limites technologiques d&rsquo;alors, des scientifiques envisagent d\u00e9j\u00e0 de cr\u00e9er des \u00abmachines qui pensent\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cet environnement de frugalit\u00e9 computationnelle, un foisonnement de travaux innovants se succ\u00e8dent. Citons notamment le premier mod\u00e8le d&rsquo;un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/R\u00e9seau_de_neurones_artificiels\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9seau de neurones artificiel<\/a> introduit en 1958 [<a href=\"#2\" rel=\"nofollow\">2<\/a>]. Ou encore en 1966, le premier <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Chatbot\" target=\"_blank\" rel=\"noreferrer noopener\">agent conversationnel<\/a> <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/ELIZA\" target=\"_blank\" rel=\"noreferrer noopener\">ELIZA<\/a><\/em> [<a href=\"#3\" rel=\"nofollow\">3<\/a>]<sup data-fn=\"3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6\" class=\"fn\"><a href=\"#3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6\" id=\"3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6-link\">4<\/a><\/sup>. Dans les ann\u00e9es 1980 et 1990, l\u2019IA s&rsquo;inspire de recherches en physique ou en biologie pour d\u00e9velopper des approches novatrices destin\u00e9es \u00e0 r\u00e9soudre des probl\u00e8mes d&rsquo;une complexit\u00e9 croissante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En parall\u00e8le, la mont\u00e9e en gamme des ordinateurs permet d&rsquo;implanter des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Algorithme\" target=\"_blank\" rel=\"noopener\">algorithmes<\/a> toujours plus complexes.\u00a0Au tournant des ann\u00e9es 2000, l&rsquo;explosion des donn\u00e9es num\u00e9riques am\u00e8ne la naissance de l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Apprentissage_profond\" target=\"_blank\" rel=\"noopener\">apprentissage profond (\u00ab<em>deep learning<\/em>\u00bb)<\/a>. La marche folle est lanc\u00e9e et l&rsquo;IA s&rsquo;attaque \u00e0 des t\u00e2ches toujours plus compliqu\u00e9es (jeux d&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/\u00c9checs\" target=\"_blank\" rel=\"noopener\">\u00e9checs<\/a> ou de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Go_(jeu)\" target=\"_blank\" rel=\"noopener\">Go<\/a>, classification d&rsquo;images, etc.). L&rsquo;aboutissement arrive en novembre 2022 avec la sortie de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/ChatGPT\"><em>ChatGPT<\/em><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si d&rsquo;autres puissances travaillent aussi sur l&rsquo;IA, dans le cadre de recherches parfois rattach\u00e9es \u00e0 ce que l&rsquo;on nomme la \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Cybern\u00e9tique\" target=\"_blank\" rel=\"noreferrer noopener\">cybern\u00e9tique<\/a>\u00bb, les \u00c9tats-Unis dominent. D&rsquo;abord par un investissement massif de la recherche, notamment public. Ensuite, par l&rsquo;\u00e9mergence d&rsquo;un \u00e9cosyst\u00e8me de \u00abgrandes\u00bb universit\u00e9s am\u00e9ricaines et d&rsquo;industries, dont la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Silicon_Valley\" target=\"_blank\" rel=\"noreferrer noopener\">Silicon Valley<\/a> demeure le symbole.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Le complexe techno-militaro-industriel am\u00e9ricain<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">En fait, les premiers pas de l&rsquo;IA s&rsquo;int\u00e8grent dans un bouillonnement technologique nord-am\u00e9ricain plus large qui inclut \u00e9galement l&rsquo;\u00e9bauche d&rsquo;internet<sup data-fn=\"30b1e788-f0bb-4879-80ef-61f805e7421e\" class=\"fn\"><a href=\"#30b1e788-f0bb-4879-80ef-61f805e7421e\" id=\"30b1e788-f0bb-4879-80ef-61f805e7421e-link\">5<\/a><\/sup>. Ces travaux sont largement financ\u00e9s par le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Defense_Advanced_Research_Projects_Agency\" target=\"_blank\" rel=\"noreferrer noopener\">DARPA<\/a>, une agence am\u00e9ricaine rattach\u00e9e au <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pentagone_(\u00c9tats-Unis)\" target=\"_blank\" rel=\"noreferrer noopener\">Pentagone<\/a> dont l&rsquo;objectif consiste \u00e0 favoriser des recherches pouvant d\u00e9boucher sur des applications militaires<sup data-fn=\"78b48b61-4ae0-4907-8e20-fadf37653453\" class=\"fn\"><a href=\"#78b48b61-4ae0-4907-8e20-fadf37653453\" id=\"78b48b61-4ae0-4907-8e20-fadf37653453-link\">6<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9\u00e9e en 1958 au lendemain du lancement pat  l&rsquo;URSS du premier satellite <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Spoutnik\" target=\"_blank\" rel=\"noopener\">Spoutnik<\/a>, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Defense_Advanced_Research_Projects_Agency\" target=\"_blank\" rel=\"noreferrer noopener\">DARPA<\/a> fait partie d&rsquo;une s\u00e9rie d&rsquo;initiatives am\u00e9ricaines visant \u00e0 booster l&rsquo;innovation dans des domaines strat\u00e9giques. Conscients que la technologie constitue la garantie de leur puissance, les \u00c9tats-Unis comprennent que leur avance technologique et donc leur position g\u00e9ostrat\u00e9gique sont menac\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s le d\u00e9but, l&rsquo;IA s&rsquo;inscrit dans la bataille qui oppose les \u00c9tats-Unis \u00e0 son grand rival g\u00e9ostrat\u00e9gique de l&rsquo;\u00e9poque, l&rsquo;URSS. Ainsi, l&rsquo;une des applications inaugurales de l&rsquo;IA consiste en la traduction automatique de textes russes vers l&rsquo;anglais. Le soutien du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pentagone_(\u00c9tats-Unis)\" target=\"_blank\" rel=\"noreferrer noopener\">Pentagone<\/a> \u00e0 l&rsquo;IA n&rsquo;a jamais faibli depuis. Aujourd&rsquo;hui, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Defense_Advanced_Research_Projects_Agency\" target=\"_blank\" rel=\"noreferrer noopener\">DARPA<\/a> continue \u00e0 soutenir massivement des recherches en IA, notamment en mati\u00e8re d&rsquo;armes autonomes ou d&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Exosquelette_(humain)\" target=\"_blank\" rel=\"noreferrer noopener\">exosquelettes<\/a> pour soldats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les agences am\u00e9ricaines signent aussi de nombreux contrats avec des entreprises sp\u00e9cialis\u00e9es en IA, une mani\u00e8re d&rsquo;alimenter l&rsquo;\u00e9cosyst\u00e8me. La soci\u00e9t\u00e9 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Palantir_Technologies\" target=\"_blank\" rel=\"noopener\">Palantir Technologies<\/a> incarne bien cette forme de partenariat public-priv\u00e9. Elle propose des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Logiciel\" target=\"_blank\" rel=\"noreferrer noopener\">logiciels<\/a> de gestion de donn\u00e9es en temps r\u00e9el utilis\u00e9s par diff\u00e9rentes agences, en commen\u00e7ant par le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pentagone_(\u00c9tats-Unis)\" target=\"_blank\" rel=\"noreferrer noopener\">Pentagone<\/a>. Le grand nombre de frappes men\u00e9es par l&rsquo;aviation am\u00e9ricaine et isra\u00e9lienne contre l&rsquo;Iran aujourd&rsquo;hui serait impossible sans le traitement automatique de donn\u00e9es, laissant au passage de moins en moins de temps \u00e0 la validation humaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00c9tats-Unis m\u00e8nent diff\u00e9rentes politiques visant \u00e0 conserver leur avance technologique par rapport \u00e0 leurs adversaires g\u00e9ostrat\u00e9giques, notamment la Chine. En 2022, le <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/CHIPS_and_Science_Act\" target=\"_blank\" rel=\"noreferrer noopener\">CHIPS and Science Act<\/a><\/em> poursuit en partie l&rsquo;objectif de relancer une production am\u00e9ricaine de semi-conducteurs. D\u00e8s le d\u00e9but de son second mandat, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Donald_Trump\" target=\"_blank\" rel=\"noreferrer noopener\">Donald Trump<\/a> valide un projet d&rsquo;infrastructures pour l&rsquo;IA. Et durant l&rsquo;\u00e9t\u00e9 2025, son\u00a0gouvernement orchestre le sauvetage d&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Intel\" target=\"_blank\" rel=\"noreferrer noopener\">Intel<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;autre strat\u00e9gie \u00e9tasunienne consiste \u00e0 limiter l&rsquo;acc\u00e8s de la Chine aux <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\" target=\"_blank\" rel=\"noreferrer noopener\">processeurs graphiques<\/a> de derni\u00e8res g\u00e9n\u00e9rations indispensables pour la construction de gros mod\u00e8les d&rsquo;IA, d&rsquo;une part, en contr\u00f4lant ce que la constructeur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nvidia\" target=\"_blank\" rel=\"noreferrer noopener\">Nvidia<\/a> peut livrer (mod\u00e8les et quantit\u00e9s), d&rsquo;autre part, en faisant pression sur l&rsquo;entreprise n\u00e9erlandaise <a href=\"https:\/\/fr.wikipedia.org\/wiki\/ASML\" target=\"_blank\" rel=\"noreferrer noopener\">ASML<\/a> pour ne pas exporter ses machines de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Photolithographie\">photolithographie<\/a> vers la Chine, privant (pour l&rsquo;instant) cette derni\u00e8re d&rsquo;une capacit\u00e9 \u00e0 produire des processeurs ultra-puissants<sup data-fn=\"fc35af15-dad3-489d-92bb-f2296937116e\" class=\"fn\"><a href=\"#fc35af15-dad3-489d-92bb-f2296937116e\" id=\"fc35af15-dad3-489d-92bb-f2296937116e-link\">7<\/a><\/sup>.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">La r\u00e9ponse chinoise<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Les autorit\u00e9s chinoises ont \u00e9videmment bien saisi l&rsquo;importance d&rsquo;acc\u00e9der \u00e0 une ind\u00e9pendance concernant l&rsquo;IA, non seulement pour disposer \u00e0 terme d&rsquo;une arm\u00e9e capable de rivaliser avec celle des \u00c9tats-Unis, mais aussi pour doper son industrie. Outre les usages de l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Intelligence_artificielle_g\u00e9n\u00e9rative\" target=\"_blank\" rel=\"noreferrer noopener\">IA g\u00e9n\u00e9rative<\/a>, il s&rsquo;agit \u00e9galement de consolider son secteur de la robotique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Chine investit massivement dans un secteur universitaire performant, notamment dans la recherche<sup data-fn=\"250debca-9888-460b-b44f-dd5ed4580e4e\" class=\"fn\"><a href=\"#250debca-9888-460b-b44f-dd5ed4580e4e\" id=\"250debca-9888-460b-b44f-dd5ed4580e4e-link\">8<\/a><\/sup>. \u00c0 tel point qu&rsquo;elle serait sur le point de s&rsquo;imposer comme le leader en mati\u00e8re de publications scientifiques<sup data-fn=\"8a56f560-9a6a-4b17-830f-44345afcdba5\" class=\"fn\"><a href=\"#8a56f560-9a6a-4b17-830f-44345afcdba5\" id=\"8a56f560-9a6a-4b17-830f-44345afcdba5-link\">9<\/a><\/sup> [<a href=\"#4\" rel=\"nofollow\">4<\/a>]. Les succ\u00e8s r\u00e9cents de ses missions lunaires incarnent sans doute cette mont\u00e9e en puissance scientifique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec une population de plus d&rsquo;un milliard d&rsquo;individus, la Chine dispose d&rsquo;un r\u00e9servoir immense pour former des chercheureuses de pointe. De plus, son programme \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Programme_\u00ab_1_000_talents_\u00bb\" target=\"_blank\" rel=\"noreferrer noopener\">1000 talents<\/a>\u00bb recrute des chercheureuses de l&rsquo;\u00e9tranger pour acc\u00e9l\u00e9rer le transfert de connaissances. Limit\u00e9 dans un premier temps aux \u00abChinois de l\u2019\u00e9tranger\u00bb, le programme s&rsquo;adresse d\u00e9sormais \u00e0 tout le monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mati\u00e8re d&rsquo;IA, la Chine dispose d\u00e9sormais de sp\u00e9cialistes en quantit\u00e9 suffisante pour d\u00e9velopper son propre \u00e9cosyst\u00e8me. La soci\u00e9t\u00e9 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\">DeepSeek<\/a> montre que, malgr\u00e9 un acc\u00e8s restreint aux <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\" target=\"_blank\" rel=\"noreferrer noopener\">processeurs graphiques<\/a> ultra-performants, la Chine rivalise d\u00e9sormais avec les \u00c9tats-Unis. Outre le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Grand_mod\u00e8le_de_langage\" target=\"_blank\" rel=\"noreferrer noopener\">grand mod\u00e8le de langage<\/a> <em>DeepSeek<\/em>, on peut \u00e9galement citer <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Qwen\" target=\"_blank\" rel=\"noreferrer noopener\">Qwen<\/a><\/em> d&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alibaba_Group\" target=\"_blank\" rel=\"noreferrer noopener\">Alibaba<\/a> ou encore<em> Ernie<\/em> de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Baidu\" target=\"_blank\" rel=\"noreferrer noopener\">Baidu<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Surtout, l&rsquo;exp\u00e9rience <a href=\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\" target=\"_blank\" rel=\"noreferrer noopener\">DeepSeek<\/a> rappelle que l&rsquo;on peut partiellement compenser un manque en <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\" target=\"_blank\" rel=\"noreferrer noopener\">processeurs graphiques<\/a> les plus r\u00e9cents. D&rsquo;abord, en exploitant au mieux les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\" target=\"_blank\" rel=\"noreferrer noopener\">processeurs<\/a> dont on dispose : en \u00e9tudiant leur architecture, les sp\u00e9cialistes logiciels de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\" target=\"_blank\" rel=\"noreferrer noopener\">DeepSeek<\/a> optimisent le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\" target=\"_blank\" rel=\"noreferrer noopener\">code informatique<\/a> ex\u00e9cutant les mod\u00e8les<sup data-fn=\"f50389c9-99ec-4984-bcc7-e4e4a2b09a11\" class=\"fn\"><a href=\"#f50389c9-99ec-4984-bcc7-e4e4a2b09a11\" id=\"f50389c9-99ec-4984-bcc7-e4e4a2b09a11-link\">10<\/a><\/sup>. Ensuite, en entra\u00eenant astucieusement son mod\u00e8le, ici via l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Apprentissage_par_renforcement\" target=\"_blank\" rel=\"noreferrer noopener\">apprentissage par renforcement<\/a> [<a href=\"#5\" rel=\"nofollow\">5<\/a>]<sup data-fn=\"2ed4c47e-af87-4e4c-a3b5-f8afe976608a\" class=\"fn\"><a href=\"#2ed4c47e-af87-4e4c-a3b5-f8afe976608a\" id=\"2ed4c47e-af87-4e4c-a3b5-f8afe976608a-link\">11<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notons au passage que, contrairement \u00e0 une id\u00e9e re\u00e7ue, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\" target=\"_blank\" rel=\"noreferrer noopener\">DeepSeek<\/a> peut compter sur une \u00e9quipe de plusieurs centaines de chercheureuses pour d\u00e9velopper ses mod\u00e8les (plus de 190 auteurices pour le seul article scientifique de septembre 2025). Il semble clair que l&rsquo;entreprise compte sur un soutien sans faille de l&rsquo;\u00c9tat chinois.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Distille, Baby, Distille !<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le document am\u00e9ricain cit\u00e9 en ouverture de ce billet, ce n&rsquo;est pas tant l&rsquo;innovation chinoise, bien r\u00e9elle, qui est d\u00e9nonc\u00e9e mais plut\u00f4t un \u00abpiratage\u00bb des mod\u00e8les am\u00e9ricains. Plus particuli\u00e8rement, c&rsquo;est la technique de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Distillation_des_connaissances\" target=\"_blank\" rel=\"noreferrer noopener\">distillation<\/a> qui est point\u00e9e du doigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avant d&rsquo;en expliquer le principe, il convient de rappeler qu&rsquo;un mod\u00e8le d&rsquo;IA est une \u00e9quation math\u00e9matique form\u00e9e de (milliers) de milliards de param\u00e8tres fix\u00e9s lors de l&rsquo;apprentissage pour coller au mieux aux donn\u00e9es fournies comme exemples. L&rsquo;importance de ces param\u00e8tres est telle que les grands mod\u00e8les am\u00e9ricains ne communiquent pas leur valeur (on parle de mod\u00e8les ferm\u00e9s)<sup data-fn=\"f9bdd6bf-17d6-47ca-96b4-bc0758567d09\" class=\"fn\"><a href=\"#f9bdd6bf-17d6-47ca-96b4-bc0758567d09\" id=\"f9bdd6bf-17d6-47ca-96b4-bc0758567d09-link\">12<\/a><\/sup>. Et retrouver les \u00abbonnes\u00bb valeurs de ces param\u00e8tres demande beaucoup de donn\u00e9es d&rsquo;entra\u00eenement et une certaine puissance de calcul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faisons un parall\u00e8le avec l&rsquo;enseignement. Des chercheureuses n\u00e9cessitent une abondante litt\u00e9rature scientifique (donn\u00e9es d&rsquo;apprentissage) et beaucoup de travail (puissance de calcul) pour acqu\u00e9rir leur expertise. Pour autant, lorsque ces chercheureuses donnent des cours, ils et elles pr\u00e9sentent une synth\u00e8se qui permet \u00e0 des \u00e9tudiantes et \u00e9tudiants d&rsquo;acqu\u00e9rir ces expertises en utilisant une quantit\u00e9 moindre de litt\u00e9rature scientifique et de temps de travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est le principe de l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Distillation_des_connaissances\" target=\"_blank\" rel=\"noreferrer noopener\">apprentissage par distillation<\/a>. Un mod\u00e8le E (\u00e9tudiant\/\u00e9tudiante) utilise un autre mod\u00e8le C (cherchereuse) pour g\u00e9n\u00e9rer des questions et les r\u00e9ponses d\u00e9taill\u00e9es correspondantes. Le mod\u00e8le E r\u00e9pond aux questions et compare ensuite ses r\u00e9ponses \u00e0 celles du mod\u00e8le C. Le mod\u00e8le E adapte ensuite ses param\u00e8tres pour reproduire les r\u00e9ponses du mod\u00e8le C. Si on suppose que le mod\u00e8le C pr\u00e9existe, le co\u00fbt d&rsquo;apprentissage du mod\u00e8le E est comparativement (beaucoup) plus faible<sup data-fn=\"a5983dac-f766-43fa-883d-a014a22257b3\" class=\"fn\"><a href=\"#a5983dac-f766-43fa-883d-a014a22257b3\" id=\"a5983dac-f766-43fa-883d-a014a22257b3-link\">13<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et c&rsquo;est bien cette accusation que porte le gouvernement am\u00e9ricain : des entreprises chinoises utilisent des mod\u00e8les d&rsquo;IA am\u00e9ricains, en violant parfois les conditions d&rsquo;utilisation et les obligations de paiement, pour construire leurs propres mod\u00e8les d&rsquo;IA \u00e0 moindres frais par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Distillation_des_connaissances\" target=\"_blank\" rel=\"noreferrer noopener\">distillation<\/a>. Ensuite, ces mod\u00e8les viennent concurrencer ceux des entreprises am\u00e9ricaines sur les march\u00e9s mondiaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans un <a href=\"https:\/\/www.francq.info\/index.php\/blog\/2025-12\/\" rel=\"nofollow\">pr\u00e9c\u00e9dent billet<\/a> j&rsquo;avais expliqu\u00e9 comment les grands mod\u00e8les d&rsquo;IA, en particulier am\u00e9ricains, pillent les contenus cr\u00e9\u00e9s par des humains pour construire leurs mod\u00e8les, ceux-l\u00e0 m\u00eame amen\u00e9s \u00e0 remplacer ces humains ensuite. On est donc en pr\u00e9sence de l&rsquo;arroseur arros\u00e9, puisque ce sont d\u00e9sormais les mod\u00e8les am\u00e9ricains qui se retrouvent \u00abmaraud\u00e9s\u00bb \u00e0 leur tour.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Et les autres ?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Si les \u00c9tats-Unis et la Chine se disputent aujourd&rsquo;hui le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Maillot_jaune\" target=\"_blank\" rel=\"noopener\">maillot jaune<\/a> de l&rsquo;IA, les autres r\u00e9gions du monde sont tout autant conscientes de l&rsquo;importance de disposer d&rsquo;une strat\u00e9gie IA convaincante et d&rsquo;une autonomie en la mati\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;Europe dispose de nombreux atouts, dont un syst\u00e8me universitaire et de recherche qui reste excellent malgr\u00e9 les politiques de restrictions budg\u00e9taires qui rendent de plus en plus difficile son adaptation \u00e0 la massification de l&rsquo;enseignement sup\u00e9rieur et aux enjeux scientifiques modernes. Si certains cerveaux partent aux \u00c9tats-Unis pour y peupler les postes acad\u00e9miques et les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Start-up\" target=\"_blank\" rel=\"noopener\">start-ups<\/a>, d&rsquo;autres font le chemin inverse. La soci\u00e9t\u00e9 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mistral_AI\" target=\"_blank\" rel=\"noopener\">Mistral AI<\/a> ou encore <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Yann_Le_Cun\" target=\"_blank\" rel=\"noopener\">Yann Le Cun<\/a> qui fonde <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Advanced_Machine_Intelligence_Labs\" target=\"_blank\" rel=\"noopener\">Advanced Machine Intelligence Labs<\/a> fin 2025 en sont des exemples.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certaines p\u00e9tromonarchies du Golfe tentent d&rsquo;anticiper une future, m\u00eame si encore beaucoup trop \u00e9loign\u00e9e, sortie des ressources \u00e9nerg\u00e9tiques fossiles en profitant de leur manne financi\u00e8re actuelle pour investir dans l&rsquo;IA [<a href=\"#6\" rel=\"nofollow\">6<\/a>]. C&rsquo;est le cas notamment des \u00c9mirats arabes unis et de l&rsquo;Arabie saoudite qui construisent des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Grappe_de_serveurs\" target=\"_blank\" rel=\"noopener\">fermes de calcul<\/a> h\u00e9bergeant des processeurs <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nvidia\" target=\"_blank\" rel=\"noreferrer noopener\">Nvidia<\/a> dernier cri. Ils tentent aussi d&rsquo;app\u00e2ter des chercheureuses et des entreprises \u00e9trang\u00e8res sp\u00e9cialis\u00e9es en IA. Mais les r\u00e9sultats ne sont pas encore au rendez-vous, et la guerre actuelle dans la r\u00e9gion complique encore plus la situation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;Inde, qui a accueilli le dernier Sommet Mondial sur l&rsquo;IA en f\u00e9vrier 2026, cherche \u00e9galement \u00e0 s&rsquo;affirmer comme un acteur incontournable de l&rsquo;IA, m\u00eame si ses tentatives semblent ne pas porter leurs fruits pour le moment [<a href=\"#7\" rel=\"nofollow\">7<\/a>]. Voisine de la Chine, avec laquelle elle entretient des relations compliqu\u00e9es (faites de coop\u00e9ration \u00e9conomique au sein des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/BRICS%2B\" target=\"_blank\" rel=\"noopener\">BRICS+<\/a> et de litiges frontaliers), l&rsquo;Inde est condamn\u00e9e \u00e0 s&rsquo;affranchir des d\u00e9pendances \u00e9trang\u00e8res. Avec son immense population et l&rsquo;am\u00e9lioration continue de son secteur de la recherche, elle dispose indiscutablement des ressources pour relever le d\u00e9fi de l&rsquo;IA.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Une IA r\u00e9ellement ouverte et r\u00e9gul\u00e9e<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Pour autant, penser l&rsquo;\u00e9volution de l&rsquo;IA uniquement en termes de confrontations g\u00e9ostrat\u00e9giques ne constitue pas la seule voie pour assurer un acc\u00e8s \u00e9gal \u00e0 l&rsquo;IA. Au contraire, les \u00c9tats pourraient favoriser une recherche publique commune en mati\u00e8re d&rsquo;IA. \u00c0 l&rsquo;image du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Organisation_europ\u00e9enne_pour_la_recherche_nucl\u00e9aire\" target=\"_blank\" rel=\"noopener\">CERN<\/a> pour la physique des particules, un centre de recherche international offrirait une r\u00e9elle alternative \u00e0 la guerre technologique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme je l&rsquo;ai indiqu\u00e9 dans mon <a href=\"https:\/\/www.francq.info\/index.php\/blog\/2026-04\/\" rel=\"nofollow\">dernier billet<\/a>, n&rsquo;en d\u00e9plaise \u00e0 tous les nationalistes du monde, une collaboration internationale s&rsquo;av\u00e8re \u00e9galement indispensable pour une r\u00e9gulation efficace de l&rsquo;IA dans l&rsquo;int\u00e9r\u00eat de tous et de toutes. M\u00eame si les diff\u00e9rentes entit\u00e9s peuvent prendre des mesures locales concr\u00e8tes, la facilit\u00e9 avec laquelle des mod\u00e8les d&rsquo;IA se diffusent<sup data-fn=\"8209fd41-95ad-4476-8775-785da7ade05d\" class=\"fn\"><a href=\"#8209fd41-95ad-4476-8775-785da7ade05d\" id=\"8209fd41-95ad-4476-8775-785da7ade05d-link\">14<\/a><\/sup> limite l&rsquo;impact de telles initiatives.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malheureusement, une part croissante des puissances mondiales (\u00c9tats-Unis, Chine, Russie, Inde, diff\u00e9rents pays europ\u00e9ens, etc.) choisissent de miser sur la force et la brutalit\u00e9 (souvent agr\u00e9ment\u00e9es de vulgarit\u00e9). L&rsquo;histoire a pourtant maintes fois d\u00e9montr\u00e9 que ce chemin aboutissait toujours \u00e0 une impasse. Une le\u00e7on que nous ne semblons toujours pas avoir assimil\u00e9e. Mais ceci est une autre histoire\u2026<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">R\u00e9f\u00e9rences<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"1\">[1] Victor Storchan, \u00ab<a href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/24\/la-note-qui-annonce-une-nouvelle-phase-dans-la-guerre-de-lia\/\" target=\"_blank\" rel=\"noreferrer noopener\">La note qui annonce une nouvelle phase dans la guerre de l\u2019IA<\/a>\u00bb,\u00a0<em>Le Grand Continent<\/em>, 24\/04\/2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"2\">[2] Frank Rosenblatt, \u00abThe Perceptron: A Probabilistic Model for Information Storage and Organization in the Brain\u00bb,\u00a0<em>Psychological Review<\/em>,\u00a065(6), pp. 386\u2011408, 1958.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"3\">[3] Joseph Weizenbaum, \u00abELIZA &#8212; a computer program for the study of natural language communication between man and machine\u00bb,\u00a0<em>Communications of the ACM<\/em>,\u00a09(1), pp. 36\u201145, 1966.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[4] Abhishek Nagaraj &amp; Randol Yao, \u00abThe Geography of Science\u00bb, Working Paper N<sup>o<\/sup>\u00a034694, National Bureau of Economic Research, 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"5\">[5] Daya Guo,  Dejian Yang, Haowei Zhang, et al., \u00abDeepSeek-R1 Incentivizes Reasoning in LLMs through Reinforcement Learning\u00bb,\u00a0<em>Nature<\/em>, 645(8081), pp. 633\u201138, 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"6\">[6] Chloe Cornish, Ahmed Al Omran, &amp; Melissa Heikkil\u00e4, \u00abCan the Gulf really become an AI superpower?\u00bb,\u00a0<em>Financial Times<\/em>, 01\/06\/2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"7\">[7] Krishn Kaushik, \u00abIndia\u2019s AI ambitions hit limits at global summit\u00bb,\u00a0<em>Financial Times<\/em>, 22\/02\/2026.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Notes<\/h5>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"c8134819-4d19-4502-bf72-fd51380dc692\">La politique chinoise de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Donald_Trump\" target=\"_blank\" rel=\"noreferrer noopener\">Donald Trump<\/a> en ce d\u00e9but de second mandat est plus sinueuse. Elle oscille entre des p\u00e9riodes d&rsquo;affrontements et des tentatives pour trouver des \u00abdeals\u00bb (notamment en acceptant certaines exportations li\u00e9es \u00e0 l&rsquo;IA vers la Chine). <a href=\"#c8134819-4d19-4502-bf72-fd51380dc692-link\" aria-label=\"Aller \u00e0 la note de bas de page 1\">\u21a9\ufe0e<\/a><\/li><li id=\"4ed391cf-4520-4c2c-ae83-af4fdb829831\">Il est certainement encore beaucoup trop t\u00f4t pour mesurer pleinement la mani\u00e8re dont l&rsquo;IA actuelle bouleversera nos soci\u00e9t\u00e9s. Ses limites actuelles ne seront peut-\u00eatre pas aussi facilement d\u00e9pass\u00e9es que le pensent les entreprises du num\u00e9rique. De plus, la soutenabilit\u00e9 \u00e9nerg\u00e9tique d&rsquo;une IA bas\u00e9e sur des mod\u00e8les toujours plus gourmands n&rsquo;est pas acquise. Enfin, personne ne sait comment r\u00e9agiront les populations si l&rsquo;IA venait \u00e0 remplacer de nombreux emplois humains. <a href=\"#4ed391cf-4520-4c2c-ae83-af4fdb829831-link\" aria-label=\"Aller \u00e0 la note de bas de page 2\">\u21a9\ufe0e<\/a><\/li><li id=\"7b5c8010-dc7a-48e6-a1ba-a58e518e0153\">Ces chercheurs s&rsquo;inscrivent en r\u00e9alit\u00e9 dans une perspective plus longue qui inclut, <em>a minima<\/em>, les travaux de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Charles_Babbage\" target=\"_blank\" rel=\"noreferrer noopener\">Charles Babbage<\/a> et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ada_Lovelace\" target=\"_blank\" rel=\"noreferrer noopener\">Ada Lovelace<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Norbert_Wiener\" target=\"_blank\" rel=\"noreferrer noopener\">Norbert Wiener<\/a> et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alan_Turing\" target=\"_blank\" rel=\"noreferrer noopener\">Alan Turing<\/a>. Mais on pourrait certainement remonter encore plus loin (notamment avec les premiers automates). <a href=\"#7b5c8010-dc7a-48e6-a1ba-a58e518e0153-link\" aria-label=\"Aller \u00e0 la note de bas de page 3\">\u21a9\ufe0e<\/a><\/li><li id=\"3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6\">Son auteur, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Joseph_Weizenbaum\" target=\"_blank\" rel=\"noreferrer noopener\">Joseph Weizenbaum<\/a>, insiste sur le c\u00f4t\u00e9 inintelligent de son mod\u00e8le (bas\u00e9 essentiellement sur l&rsquo;identification de mots-cl\u00e9s et de certaines formulations) et sur le fait que donner l&rsquo;illusion d&rsquo;un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Logiciel\" target=\"_blank\" rel=\"noreferrer noopener\">logiciel<\/a> qui converse n&rsquo;implique nullement une intelligence dans le chef de la machine. Un avertissement toujours aussi pertinent aujourd&rsquo;hui. <a href=\"#3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6-link\" aria-label=\"Aller \u00e0 la note de bas de page 4\">\u21a9\ufe0e<\/a><\/li><li id=\"30b1e788-f0bb-4879-80ef-61f805e7421e\">Le r\u00e9seau <a href=\"https:\/\/fr.wikipedia.org\/wiki\/ARPANET\" target=\"_blank\" rel=\"noreferrer noopener\">ARPANET<\/a> qui relie les principaux calculateurs des universit\u00e9s am\u00e9ricaines dans les ann\u00e9es 1960 donne naissance aux technologies sur lesquelles internet se base par la suite. <a href=\"#30b1e788-f0bb-4879-80ef-61f805e7421e-link\" aria-label=\"Aller \u00e0 la note de bas de page 5\">\u21a9\ufe0e<\/a><\/li><li id=\"78b48b61-4ae0-4907-8e20-fadf37653453\">Le DARPA a \u00e9galement jou\u00e9 un r\u00f4le consid\u00e9rable dans le domaine des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Microprocesseur\" target=\"_blank\" rel=\"noopener\">microprocesseurs<\/a> et des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Interface_graphique\" target=\"_blank\" rel=\"noopener\">interfaces graphiques<\/a>. <a href=\"#78b48b61-4ae0-4907-8e20-fadf37653453-link\" aria-label=\"Aller \u00e0 la note de bas de page 6\">\u21a9\ufe0e<\/a><\/li><li id=\"fc35af15-dad3-489d-92bb-f2296937116e\">Pour faire simple, afin d&rsquo;am\u00e9liorer les performances d&rsquo;un processeur, il faut multiplier le nombre de composants int\u00e9gr\u00e9s, ce qui suppose de graver toujours plus fin. Actuellement, seul <a href=\"https:\/\/fr.wikipedia.org\/wiki\/ASML\" target=\"_blank\" rel=\"noreferrer noopener\">ASML<\/a> propose les machines indispensables pour atteindre les finesses de gravure extr\u00eames. <a href=\"#fc35af15-dad3-489d-92bb-f2296937116e-link\" aria-label=\"Aller \u00e0 la note de bas de page 7\">\u21a9\ufe0e<\/a><\/li><li id=\"250debca-9888-460b-b44f-dd5ed4580e4e\">L&rsquo;excellence acad\u00e9mique chinoise r\u00e9elle ne peut masquer les in\u00e9galit\u00e9s abyssales existantes entre les grandes institutions et le reste des universit\u00e9s, ainsi que les faibles d\u00e9bouch\u00e9s que propose le pays aux dipl\u00f4m\u00e9s du sup\u00e9rieur (ce qui pourrait devenir un s\u00e9rieux probl\u00e8me politique). <a href=\"#250debca-9888-460b-b44f-dd5ed4580e4e-link\" aria-label=\"Aller \u00e0 la note de bas de page 8\">\u21a9\ufe0e<\/a><\/li><li id=\"8a56f560-9a6a-4b17-830f-44345afcdba5\">Les r\u00e9sultats actuels de la Chine ne doivent pas faire oublier que la probl\u00e9matique de la fraude scientifique caract\u00e9rise encore le monde acad\u00e9mique chinois (mais pas seulement). Notons que depuis quelques ann\u00e9es les autorit\u00e9s s&rsquo;attellent r\u00e9ellement \u00e0 la combattre. <a href=\"#8a56f560-9a6a-4b17-830f-44345afcdba5-link\" aria-label=\"Aller \u00e0 la note de bas de page 9\">\u21a9\ufe0e<\/a><\/li><li id=\"f50389c9-99ec-4984-bcc7-e4e4a2b09a11\">Quand on dispose en permanence des derniers <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\" target=\"_blank\" rel=\"noreferrer noopener\">processeurs graphiques<\/a>, on peut se permettre de ne pas perfectionner le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\" target=\"_blank\" rel=\"noreferrer noopener\">code informatique<\/a>, la technologie assurant les accroissements de performances. Par contre, lorsqu&rsquo;on n&rsquo;acc\u00e8de qu&rsquo;\u00e0 des mod\u00e8les moins puissants, le seul moyen pour am\u00e9liorer les performances consiste \u00e0 accro\u00eetre l&rsquo;efficacit\u00e9 du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\" target=\"_blank\" rel=\"noreferrer noopener\">code informatique<\/a>. <a href=\"#f50389c9-99ec-4984-bcc7-e4e4a2b09a11-link\" aria-label=\"Aller \u00e0 la note de bas de page 10\">\u21a9\ufe0e<\/a><\/li><li id=\"2ed4c47e-af87-4e4c-a3b5-f8afe976608a\">Pour faire simple, l&rsquo;id\u00e9e de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\" target=\"_blank\" rel=\"noreferrer noopener\">DeepSeek<\/a> est de demander \u00e0 son mod\u00e8le de g\u00e9n\u00e9rer des r\u00e9ponses incluant des \u00e9tapes interm\u00e9diaires puis, en comparant ces \u00e9tapes avec des r\u00e9ponses connues, \u00e0 p\u00e9naliser ou gratifier le mod\u00e8le suivant les \u00e9carts entre \u00e9tapes produites et \u00e9tapes r\u00e9elles. <a href=\"#2ed4c47e-af87-4e4c-a3b5-f8afe976608a-link\" aria-label=\"Aller \u00e0 la note de bas de page 11\">\u21a9\ufe0e<\/a><\/li><li id=\"f9bdd6bf-17d6-47ca-96b4-bc0758567d09\">Les valeurs des param\u00e8tres ainsi que le donn\u00e9es utilis\u00e9es pour l&rsquo;apprentissage constituent le v\u00e9ritable secret des fournisseurs de mod\u00e8les d&rsquo;IA. C&rsquo;est la raison pour laquelle, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\" target=\"_blank\" rel=\"noreferrer noopener\">code source<\/a> des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Logiciel\" target=\"_blank\" rel=\"noreferrer noopener\">logiciels<\/a> utilis\u00e9 pour l&rsquo;apprentissage et l&rsquo;ex\u00e9cution des mod\u00e8les est souvent ouvert car, pour des entreprises comme <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Meta_(entreprise)\" target=\"_blank\" rel=\"noreferrer noopener\">Meta<\/a> ou <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alphabet_(entreprise)\" target=\"_blank\" rel=\"noreferrer noopener\">Alphabet<\/a>, il ne repr\u00e9sente pas un avantage concurrentiel. <a href=\"#f9bdd6bf-17d6-47ca-96b4-bc0758567d09-link\" aria-label=\"Aller \u00e0 la note de bas de page 12\">\u21a9\ufe0e<\/a><\/li><li id=\"a5983dac-f766-43fa-883d-a014a22257b3\">Notons que l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Distillation_des_connaissances\" target=\"_blank\" rel=\"noreferrer noopener\">apprentissage par distillation<\/a> permet aussi de construire des mod\u00e8les plus petits \u00e0 partir d&rsquo;un seul gros mod\u00e8le. \u00c0 termes, cela pourrait favoriser le d\u00e9ploiement de mod\u00e8les sp\u00e9cialis\u00e9s plus petits et donc plus rapides et moins \u00e9nergivores lors de l&rsquo;inf\u00e9rence. <a href=\"#a5983dac-f766-43fa-883d-a014a22257b3-link\" aria-label=\"Aller \u00e0 la note de bas de page 13\">\u21a9\ufe0e<\/a><\/li><li id=\"8209fd41-95ad-4476-8775-785da7ade05d\">Un mod\u00e8le d&rsquo;IA \u00e9tant en r\u00e9alit\u00e9 une s\u00e9rie de fichiers informatiques (parfois volumineux il est vrai), une simple connexion internet et un tout petit peu de patience suffisent pour t\u00e9l\u00e9charger un mod\u00e8le. <a href=\"#8209fd41-95ad-4476-8775-785da7ade05d-link\" aria-label=\"Aller \u00e0 la note de bas de page 14\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;importance prise par l&rsquo;IA au sein de nos soci\u00e9t\u00e9s, amplifi\u00e9e par les potentialit\u00e9s de l&rsquo;IA g\u00e9n\u00e9rative, transforme l&rsquo;IA en un objet de politiques g\u00e9ostrat\u00e9giques.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"\/home\/xeddixx\/www\/wp-content\/plugins\/kirki\/includes\/Frontend\/views\/template\/page.php","format":"standard","meta":{"footnotes":"[{\"content\":\"La politique chinoise de <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Donald_Trump\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Donald Trump<\/a> en ce d\u00e9but de second mandat est plus sinueuse. Elle oscille entre des p\u00e9riodes d'affrontements et des tentatives pour trouver des \u00abdeals\u00bb (notamment en acceptant certaines exportations li\u00e9es \u00e0 l'IA vers la Chine).\",\"id\":\"c8134819-4d19-4502-bf72-fd51380dc692\"},{\"content\":\"Il est certainement encore beaucoup trop t\u00f4t pour mesurer pleinement la mani\u00e8re dont l'IA actuelle bouleversera nos soci\u00e9t\u00e9s. Ses limites actuelles ne seront peut-\u00eatre pas aussi facilement d\u00e9pass\u00e9es que le pensent les entreprises du num\u00e9rique. De plus, la soutenabilit\u00e9 \u00e9nerg\u00e9tique d'une IA bas\u00e9e sur des mod\u00e8les toujours plus gourmands n'est pas acquise. Enfin, personne ne sait comment r\u00e9agiront les populations si l'IA venait \u00e0 remplacer de nombreux emplois humains.\",\"id\":\"4ed391cf-4520-4c2c-ae83-af4fdb829831\"},{\"content\":\"Ces chercheurs s'inscrivent en r\u00e9alit\u00e9 dans une perspective plus longue qui inclut, <em>a minima<\/em>, les travaux de <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Charles_Babbage\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Charles Babbage<\/a> et <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Ada_Lovelace\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Ada Lovelace<\/a>, <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Norbert_Wiener\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Norbert Wiener<\/a> et <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Alan_Turing\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Alan Turing<\/a>. Mais on pourrait certainement remonter encore plus loin (notamment avec les premiers automates).\",\"id\":\"7b5c8010-dc7a-48e6-a1ba-a58e518e0153\"},{\"content\":\"Son auteur, <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Joseph_Weizenbaum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Joseph Weizenbaum<\/a>, insiste sur le c\u00f4t\u00e9 inintelligent de son mod\u00e8le (bas\u00e9 essentiellement sur l'identification de mots-cl\u00e9s et de certaines formulations) et sur le fait que donner l'illusion d'un <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Logiciel\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">logiciel<\/a> qui converse n'implique nullement une intelligence dans le chef de la machine. Un avertissement toujours aussi pertinent aujourd'hui.\",\"id\":\"3a46cdae-ce36-4d85-bc0e-fa6077d8d8a6\"},{\"content\":\"Le r\u00e9seau <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/ARPANET\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">ARPANET<\/a> qui relie les principaux calculateurs des universit\u00e9s am\u00e9ricaines dans les ann\u00e9es 1960 donne naissance aux technologies sur lesquelles internet se base par la suite.\",\"id\":\"30b1e788-f0bb-4879-80ef-61f805e7421e\"},{\"content\":\"Le DARPA a \u00e9galement jou\u00e9 un r\u00f4le consid\u00e9rable dans le domaine des <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Microprocesseur\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">microprocesseurs<\/a> et des <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Interface_graphique\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">interfaces graphiques<\/a>.\",\"id\":\"78b48b61-4ae0-4907-8e20-fadf37653453\"},{\"content\":\"Pour faire simple, afin d'am\u00e9liorer les performances d'un processeur, il faut multiplier le nombre de composants int\u00e9gr\u00e9s, ce qui suppose de graver toujours plus fin. Actuellement, seul <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/ASML\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">ASML<\/a> propose les machines indispensables pour atteindre les finesses de gravure extr\u00eames.\",\"id\":\"fc35af15-dad3-489d-92bb-f2296937116e\"},{\"content\":\"L'excellence acad\u00e9mique chinoise r\u00e9elle ne peut masquer les in\u00e9galit\u00e9s abyssales existantes entre les grandes institutions et le reste des universit\u00e9s, ainsi que les faibles d\u00e9bouch\u00e9s que propose le pays aux dipl\u00f4m\u00e9s du sup\u00e9rieur (ce qui pourrait devenir un s\u00e9rieux probl\u00e8me politique).\",\"id\":\"250debca-9888-460b-b44f-dd5ed4580e4e\"},{\"content\":\"Les r\u00e9sultats actuels de la Chine ne doivent pas faire oublier que la probl\u00e9matique de la fraude scientifique caract\u00e9rise encore le monde acad\u00e9mique chinois (mais pas seulement). Notons que depuis quelques ann\u00e9es les autorit\u00e9s s'attellent r\u00e9ellement \u00e0 la combattre.\",\"id\":\"8a56f560-9a6a-4b17-830f-44345afcdba5\"},{\"content\":\"Quand on dispose en permanence des derniers <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Processeur_graphique\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">processeurs graphiques<\/a>, on peut se permettre de ne pas perfectionner le <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">code informatique<\/a>, la technologie assurant les accroissements de performances. Par contre, lorsqu'on n'acc\u00e8de qu'\u00e0 des mod\u00e8les moins puissants, le seul moyen pour am\u00e9liorer les performances consiste \u00e0 accro\u00eetre l'efficacit\u00e9 du <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">code informatique<\/a>.\",\"id\":\"f50389c9-99ec-4984-bcc7-e4e4a2b09a11\"},{\"content\":\"Pour faire simple, l'id\u00e9e de <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/DeepSeek\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">DeepSeek<\/a> est de demander \u00e0 son mod\u00e8le de g\u00e9n\u00e9rer des r\u00e9ponses incluant des \u00e9tapes interm\u00e9diaires puis, en comparant ces \u00e9tapes avec des r\u00e9ponses connues, \u00e0 p\u00e9naliser ou gratifier le mod\u00e8le suivant les \u00e9carts entre \u00e9tapes produites et \u00e9tapes r\u00e9elles.\",\"id\":\"2ed4c47e-af87-4e4c-a3b5-f8afe976608a\"},{\"content\":\"Les valeurs des param\u00e8tres ainsi que le donn\u00e9es utilis\u00e9es pour l'apprentissage constituent le v\u00e9ritable secret des fournisseurs de mod\u00e8les d'IA. C'est la raison pour laquelle, le <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Code_source\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">code source<\/a> des <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Logiciel\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">logiciels<\/a> utilis\u00e9 pour l'apprentissage et l'ex\u00e9cution des mod\u00e8les est souvent ouvert car, pour des entreprises comme <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Meta_(entreprise)\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Meta<\/a> ou <a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Alphabet_(entreprise)\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">Alphabet<\/a>, il ne repr\u00e9sente pas un avantage concurrentiel.\",\"id\":\"f9bdd6bf-17d6-47ca-96b4-bc0758567d09\"},{\"content\":\"Notons que l'<a href=\\\"https:\/\/fr.wikipedia.org\/wiki\/Distillation_des_connaissances\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">apprentissage par distillation<\/a> permet aussi de construire des mod\u00e8les plus petits \u00e0 partir d'un seul gros mod\u00e8le. \u00c0 termes, cela pourrait favoriser le d\u00e9ploiement de mod\u00e8les sp\u00e9cialis\u00e9s plus petits et donc plus rapides et moins \u00e9nergivores lors de l'inf\u00e9rence.\",\"id\":\"a5983dac-f766-43fa-883d-a014a22257b3\"},{\"content\":\"Un mod\u00e8le d'IA \u00e9tant en r\u00e9alit\u00e9 une s\u00e9rie de fichiers informatiques (parfois volumineux il est vrai), une simple connexion internet et un tout petit peu de patience suffisent pour t\u00e9l\u00e9charger un mod\u00e8le.\",\"id\":\"8209fd41-95ad-4476-8775-785da7ade05d\"}]"},"categories":[100],"tags":[98,109],"class_list":["post-3521","post","type-post","status-publish","format-standard","hentry","category-politic","tag-politic","tag-technologie"],"views":98,"_links":{"self":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/3521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/comments?post=3521"}],"version-history":[{"count":79,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/3521\/revisions"}],"predecessor-version":[{"id":3604,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/3521\/revisions\/3604"}],"wp:attachment":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/media?parent=3521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/categories?post=3521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/tags?post=3521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}