{"id":1611,"date":"2017-12-20T17:50:00","date_gmt":"2017-12-20T16:50:00","guid":{"rendered":"https:\/\/xeddixx.cluster029.hosting.ovh.net\/?p=1611"},"modified":"2026-02-10T10:31:16","modified_gmt":"2026-02-10T09:31:16","slug":"2017-12","status":"publish","type":"post","link":"https:\/\/www.francq.info\/index.php\/blog\/2017-12\/","title":{"rendered":"\u00c0 quand une r\u00e9elle neutralit\u00e9 du net\u00a0?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le 14 d\u00e9cembre dernier, la&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Federal_Communications_Commission\" rel=\"noreferrer noopener\">Federal Communications Commission (FCC)<\/a>, l\u2019agence f\u00e9d\u00e9rale am\u00e9ricaine charg\u00e9e de la r\u00e9gulation des t\u00e9l\u00e9communications,&nbsp;<a target=\"_blank\" href=\"https:\/\/transition.fcc.gov\/Daily_Releases\/Daily_Business\/2017\/db1214\/DOC-348261A1.pdf\" rel=\"noreferrer noopener\">annonce la fin de ce que l&rsquo;on appelle la \u00ab neutralit\u00e9 du net \u00bb<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce principe de fonctionnement d\u2019internet, en vigueur depuis ses d\u00e9buts<sup data-fn=\"ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8\" class=\"fn\"><a href=\"#ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8\" id=\"ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8-link\">1<\/a><\/sup>, incarne aux yeux de beaucoup une notion d\u2019\u00e9galit\u00e9 cens\u00e9e \u00eatre inh\u00e9rente au r\u00e9seau : que vous soyez puissant ou mis\u00e9rable, cette \u00e9galit\u00e9 doit vous garantir que vos donn\u00e9es transitent sur le r\u00e9seau avec le m\u00eame degr\u00e9 de priorit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce principe avait \u00e9galement ses d\u00e9tracteurs. \u00c0 commencer par les \u00e9ternels r\u00e9fractaires \u00e0 toute forme de r\u00e9gulation et particuli\u00e8rement leur champion du moment,&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Donald_Trump\" target=\"_blank\" rel=\"noreferrer noopener\">Donald Trump<\/a>. D\u2019autres, tels les op\u00e9rateurs de t\u00e9l\u00e9communications<sup data-fn=\"c51f6dad-f36c-422d-9a8d-41474b2eff38\" class=\"fn\"><a href=\"#c51f6dad-f36c-422d-9a8d-41474b2eff38\" id=\"c51f6dad-f36c-422d-9a8d-41474b2eff38-link\">2<\/a><\/sup>, souhaitaient que les plus gros pourvoyeurs de donn\u00e9es (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>,&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Facebook\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>,&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Netflix\" target=\"_blank\" rel=\"noreferrer noopener\">Netflix<\/a>, etc.) payent proportionnellement plus que les autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le manque de recul sur la d\u00e9cision de la&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Federal_Communications_Commission\" rel=\"noreferrer noopener\">FCC<\/a>&nbsp;emp\u00eache toute anticipation de ses cons\u00e9quences. D\u2019aucuns annoncent un internet r\u00e9serv\u00e9 aux plus riches \u2013 un risque r\u00e9el. Cet arr\u00eat constitue surtout une occasion de nous interroger, enfin, sur la nature de la r\u00e9gulation que nous voulons pour internet.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Une petite introduction technique au fonctionnement d\u2019internet<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Mais il convient d\u2019abord de distinguer le \u00abr\u00e9seau internet\u00bb des services rendus par internet&nbsp;[<a href=\"#1\" rel=\"nofollow\">1<\/a>]. En effet, chaque activit\u00e9 en ligne (naviguer, \u00e9couter de la musique en&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Streaming\" target=\"_blank\" rel=\"noreferrer noopener\">streaming<\/a>, envoyer un courriel, etc.) implique un \u00e9change de donn\u00e9es au travers d\u2019infrastructures de communication.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un internaute souhaitant lire mon dernier billet sur son smartphone \u00e9changera avec mon serveur des donn\u00e9es repr\u00e9sentant une demande (\u00abacc\u00e8s \u00e0 telle page\u00bb) puis une r\u00e9ponse (\u00abcontenu de la page\u00bb). Ces donn\u00e9es emprunteront, de plus, diff\u00e9rentes infrastructures (Wi-Fi, c\u00e2bles optiques, etc.).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour \u00eatre plus pr\u00e9cis, ces donn\u00e9es sont d\u00e9coup\u00e9es en \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Datagramme\" target=\"_blank\" rel=\"noreferrer noopener\">datagrammes<\/a>\u00bb. Chaque datagramme contient l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Adresse_IP\" target=\"_blank\" rel=\"noreferrer noopener\">adresse IP<\/a>&nbsp;de l\u2019\u00e9metteur et celle du r\u00e9cepteur. Les diff\u00e9rents datagrammes voyagent sur le r\u00e9seau en empruntant des chemins diff\u00e9rents et sont r\u00e9ordonn\u00e9s par le r\u00e9cepteur<sup data-fn=\"ae98b346-6197-4b58-9cfc-c665470e5fc7\" class=\"fn\"><a href=\"#ae98b346-6197-4b58-9cfc-c665470e5fc7\" id=\"ae98b346-6197-4b58-9cfc-c665470e5fc7-link\">3<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d\u2019activit\u00e9s simultan\u00e9es, des datagrammes de \u00abnatures diff\u00e9rentes\u00bb (textes\/images et musique) partent et arrivent du terminal de l\u2019utilisateur<sup data-fn=\"fa97db0f-27a0-49d2-9d74-9c3381c61df5\" class=\"fn\"><a href=\"#fa97db0f-27a0-49d2-9d74-9c3381c61df5\" id=\"fa97db0f-27a0-49d2-9d74-9c3381c61df5-link\">4<\/a><\/sup>. Pour diff\u00e9rencier ces \u00abnatures diff\u00e9rentes\u00bb, on associe \u00e0 chaque datagramme un nombre appel\u00e9 \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Port_(logiciel)\" target=\"_blank\" rel=\"noreferrer noopener\">port<\/a>\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 l\u2019absence de normes pour ces ports, de tr\u00e8s nombreuses conventions existent. Ainsi, le port 80 est \u00abr\u00e9serv\u00e9\u00bb pour les \u00e9changes de donn\u00e9es Web standards. Pour la musique en&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Streaming\" rel=\"noreferrer noopener\">streaming<\/a>&nbsp;par exemple,&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Spotify\" rel=\"noreferrer noopener\">Spotify<\/a><\/em>&nbsp;utilise le port 4070<em>&nbsp;<\/em>alors que&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Deezer\" rel=\"noreferrer noopener\">Deezer<\/a><\/em>&nbsp;choisit de passer par le Web (et donc le port 80).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u2019autres termes, pour chaque datagramme qui circule sur internet, on dispose de l\u2019information sur son \u00e9metteur, son r\u00e9cepteur et, le plus souvent, le service concern\u00e9 par les donn\u00e9es transport\u00e9es (\u00e0 travers le num\u00e9ro de port ou la combinaison de celui-ci et d\u2019une&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Adresse_IP\" rel=\"noreferrer noopener\">adresse IP<\/a>).<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Le principe de \u00abneutralit\u00e9 du net\u00bb<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Pourtant, en pratique, les op\u00e9rateurs n\u2019utilisent quasi jamais cette information lorsqu\u2019ils assurent le transport de datagrammes sur leurs r\u00e9seaux. Bien que cette information soit&nbsp;<em>a priori<\/em>&nbsp;utile, le principe de \u00abneutralit\u00e9 du net\u00bb en restreint fort l\u2019utilisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce principe repose sur une r\u00e8gle g\u00e9n\u00e9rale : les op\u00e9rateurs ne peuvent discriminer un datagramme sur base de l\u2019adresse de son \u00e9metteur, de celle de son r\u00e9cepteur, du type de contenu, ou d\u2019une combinaison de ces crit\u00e8res&nbsp;[<a href=\"#2\" rel=\"nofollow\">2<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le dire autrement, les op\u00e9rateurs se retrouvent restreints aux seules d\u00e9cisions techniques li\u00e9es \u00e0 l\u2019infrastructure d\u2019internet. Le principe pr\u00e9voit quelques exceptions, comme lorsque l\u2019int\u00e9grit\u00e9 du r\u00e9seau se retrouve menac\u00e9e, ou pour bloquer des contenus non sollicit\u00e9s (tels les&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Spam\" rel=\"noreferrer noopener\">pourriels<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette approche r\u00e9sulte d\u2019une opposition entre les op\u00e9rateurs et les fournisseurs en ligne (de services et\/ou de contenus). Les seconds voulant \u00e9viter que les premiers disposent d\u2019un contr\u00f4le trop important. On imagine ais\u00e9ment les dommages pour&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Netflix\" rel=\"noreferrer noopener\">Netflix<\/a>&nbsp;si un op\u00e9rateur bloquait ses contenus pour telle ou telle raison, f\u00fbt-ce de mani\u00e8re temporaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Remarquons aussi que ce principe incarne une vision somme toute assez lib\u00e9rale de la r\u00e9gulation d\u2019internet : on laisse les services et contenus en ligne rivaliser librement (en \u00e9vitant toute discrimination de datagrammes), tout en laissant la \u00abmain invisible du march\u00e9\u00bb d\u00e9cider ceux qui survivront.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>L\u2019illusion d\u2019une neutralit\u00e9 en ligne<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreux avocats de la \u00abneutralit\u00e9 du net\u00bb laissent entrevoir que la r\u00e8gle g\u00e9n\u00e9rale \u00e9nonc\u00e9e plus haut suffit \u00e0 garantir une neutralit\u00e9 en ligne effective. On comprend d\u00e8s lors que ses d\u00e9fenseurs se mobilisent autant aujourd\u2019hui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, on sait bien que cette acceptation de la \u00abneutralit\u00e9 du net\u00bb n\u2019assure en rien une r\u00e9elle neutralit\u00e9 en ligne&nbsp;[<a href=\"#3\" rel=\"nofollow\">3<\/a>], d\u2019o\u00f9 l\u2019utilisation de guillemets. J\u2019ai d\u2019ailleurs d\u00e9taill\u00e9 en d\u2019autres occasions les nombreux biais existant actuellement&nbsp;[<a href=\"#5\" rel=\"nofollow\">5<\/a>].&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je propose quant \u00e0 moi une typologie divis\u00e9e en quatre cat\u00e9gories, typologie qui \u00e9tend un cadre conceptuel de d\u00e9part pour l\u2019\u00e9tude des biais engendr\u00e9s par les syst\u00e8mes informatiques en g\u00e9n\u00e9ral&nbsp;[<a href=\"#4\" rel=\"nofollow\">4<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout d\u2019abord, des \u00abbiais pr\u00e9existants\u00bb se retrouvent \u00ab<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Intrication_quantique\" rel=\"noreferrer noopener\">intriqu\u00e9s<\/a>\u00bb aux technologies pr\u00e9sentes sur internet sans qu\u2019ils soient questionn\u00e9s. Prenons&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Google_(moteur_de_recherche)\" rel=\"noreferrer noopener\">Google Search<\/a><\/em>&nbsp;: son algorithme de classement&nbsp;<em><a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/PageRank\" rel=\"noreferrer noopener\">PageRank<\/a><\/em>&nbsp;s\u2019inspire de la bibliom\u00e9trie dont on conna\u00eet pourtant les limites depuis longtemps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet implique \u00e9videmment aussi des \u00abbiais techniques\u00bb. La propagation des datagrammes sur internet au travers des n\u0153uds\u200a<sup data-fn=\"ef33b27c-7592-430f-a00e-9f6d3ce50ae8\" class=\"fn\"><a href=\"#ef33b27c-7592-430f-a00e-9f6d3ce50ae8\" id=\"ef33b27c-7592-430f-a00e-9f6d3ce50ae8-link\">5<\/a><\/sup>&nbsp;illustre cela. La taille d\u2019internet rend impossible le calcul d\u2019un chemin optimal<sup data-fn=\"e004d03b-87cb-4ed8-b5bc-f3afa59c0c43\" class=\"fn\"><a href=\"#e004d03b-87cb-4ed8-b5bc-f3afa59c0c43\" id=\"e004d03b-87cb-4ed8-b5bc-f3afa59c0c43-link\">6<\/a><\/sup>. Il est donc&nbsp;<em>de facto<\/em>&nbsp;impossible de garantir un traitement \u00e9quitable de chaque datagramme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les internautes rencontrent \u00e9galement des \u00abbiais \u00e9mergents\u00bb qui d\u00e9coulent de pratiques d\u2019utilisation des technologies par les internautes qui n\u2019avaient pas \u00e9t\u00e9 anticip\u00e9es au d\u00e9part et qui d\u00e9naturent parfois quelque peu la conception originale de ces technologies.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les\u00a0<a href=\"https:\/\/www.francq.info\/index.php\/blog\/2017-11.html\" target=\"_blank\" rel=\"noreferrer noopener\">notations omnipr\u00e9sents en ligne<\/a>\u00a0(de produits, de commentaires, etc.) exemplifient cela. L\u2019id\u00e9e initiale consiste \u00e0 d\u00e9duire une \u00abqualit\u00e9\u00bb \u00e0 partir de jugements \u00abautonomes\u00bb effectu\u00e9s par les internautes. Mais, en r\u00e9alit\u00e9, ceux-ci sont fortement influenc\u00e9s par les jugements d\u00e9j\u00e0 \u00e9mis et visibles en ligne\u00a0[<a href=\"#6\" rel=\"nofollow\">6<\/a>,\u00a0<a href=\"#7\" rel=\"nofollow\">7<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, de nombreux \u00abbiais financiers\u00bb traversent internet et r\u00e9sultent de disparit\u00e9s financi\u00e8res entre les diff\u00e9rents acteurs. Ces biais trouvent leur origine dans le d\u00e9veloppement capitalistique d\u2019internet&nbsp;[<a href=\"#8\" rel=\"nofollow\">8<\/a>]<sup data-fn=\"90d69fc0-dc46-4b58-b598-11909f96d695\" class=\"fn\"><a href=\"#90d69fc0-dc46-4b58-b598-11909f96d695\" id=\"90d69fc0-dc46-4b58-b598-11909f96d695-link\">7<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Citons ainsi la r\u00e9activit\u00e9 d\u2019un site Web qui d\u00e9termine partiellement son succ\u00e8s. En pratique, cette r\u00e9activit\u00e9 d\u00e9pend non seulement de la vitesse de transport des datagrammes (<em>a priori<\/em>&nbsp;identique pour chaque site), mais \u00e9galement de la puissance des serveurs : la capacit\u00e9 d\u2019investissement influence donc le succ\u00e8s d\u2019un site. Et je ne parle pas des nombreuses fractures num\u00e9riques socio-\u00e9conomiques.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Une remise en question de la \u00abneutralit\u00e9 du net\u00bb<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Au vu de tous ces biais en ligne malgr\u00e9 l\u2019application stricte du principe de \u00abneutralit\u00e9 du net\u00bb en vigueur jusqu\u2019ici, on peut raisonnablement s\u2019interroger sur l\u2019opportunit\u00e9 de maintenir une mise en \u0153uvre visant \u00e0 ce degr\u00e9 d\u2019orthodoxe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rateurs remettent ce principe en cause depuis longtemps. Pour financer les infrastructures futures r\u00e9pondant aux nouvelles pratiques en ligne (comme la vid\u00e9o en&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Streaming\" rel=\"noreferrer noopener\">streaming<\/a>), ils affirment que celles-ci n\u00e9cessitent des rentr\u00e9es nouvelles, car un risque de rupture dans la qualit\u00e9 de l\u2019acheminement des donn\u00e9es existerait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019inspirant du&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Principe_pollueur-payeur\" rel=\"noreferrer noopener\">principe pollueur-payeur<\/a>, ils souhaiteraient faire payer plus les gros \u00e9metteurs de donn\u00e9es. Cette demande n\u2019est pas forc\u00e9ment ill\u00e9gitime. Apr\u00e8s tout, les grands fournisseurs de services en ligne sont \u00e9galement ceux qui g\u00e9n\u00e8rent le plus de revenus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mise en place d\u2019une tarification asym\u00e9trique m\u00e9rite donc qu\u2019on y r\u00e9fl\u00e9chisse pour autant qu\u2019elle s\u2019accompagne d\u2019un cadre g\u00e9n\u00e9ral d\u2019application. La possibilit\u00e9 d\u2019appliquer des tarifs diff\u00e9renci\u00e9s pourrait, par exemple, s\u2019accompagner d\u2019une obligation pour les op\u00e9rateurs de mieux desservir certaines zones&nbsp;[<a href=\"#5\" rel=\"nofollow\">5<\/a>].&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je milite depuis longtemps pour la mise en place d\u2019agences de r\u00e9gulation ind\u00e9pendantes&nbsp;[<a href=\"#5\" rel=\"nofollow\">5<\/a>]. Celles-ci v\u00e9rifieraient notamment que les op\u00e9rateurs ne profitent pas d\u2019une position de monopole et assureraient que certains fournisseurs d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral (tels&nbsp;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Wikip%C3%A9dia\" target=\"_blank\" rel=\"noreferrer noopener\">Wikip\u00e9dia<\/a><\/em>) ne soient pas vis\u00e9s.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>La \u00abneutralit\u00e9 du net\u00bb comme r\u00e8gle absolue<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Si une stricte observance du principe de \u00abneutralit\u00e9 du net\u00bb appara\u00eet excessive, voire s\u2019av\u00e8re contre-productive, comment expliquer l\u2019importance que lui accordent ses plus fervents d\u00e9fenseurs ? Il me semble qu\u2019on peut identifier trois cat\u00e9gories de partisans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Historiquement, l\u2019esprit libertaire des\u00a0<a href=\"https:\/\/www.francq.info\/index.php\/blog\/2015-10.html\" rel=\"nofollow\">hackers<\/a>\u00a0impr\u00e8gne la gestion du r\u00e9seau. Ils con\u00e7oivent les protocoles, d\u00e9veloppent les premi\u00e8res applications et assurent les services de base\u00a0[<a href=\"#1\" rel=\"nofollow\">1<\/a>]. Cette vision se cristallise dans la \u00ab<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/D%C3%A9claration_d%27ind%C3%A9pendance_du_cyberespace\" target=\"_blank\" rel=\"noreferrer noopener\">d\u00e9claration d&rsquo;ind\u00e9pendance du Cyberespace<\/a><\/em>\u00bb de\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/John_Perry_Barlow\" target=\"_blank\" rel=\"noreferrer noopener\">John Perry Barlow<\/a>\u00a0[<a href=\"#9\" rel=\"nofollow\">9<\/a>].\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019op\u00e9rateur&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/AT%26T\" target=\"_blank\" rel=\"noreferrer noopener\">AT&amp;T<\/a>&nbsp;n\u2019est d\u2019abord qu\u2019un simple contractant \u00e0 qui des fonds publics am\u00e9ricains louent des lignes d\u00e9di\u00e9es pour transmettre les donn\u00e9es, et n\u2019intervient pas du tout dans la gestion. Ce n\u2019est qu\u2019avec la lib\u00e9ralisation d\u2019internet amorc\u00e9e dans les ann\u00e9es 1990 que les op\u00e9rateurs prennent de l\u2019importance&nbsp;[<a href=\"#1\" rel=\"nofollow\">1<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l\u2019\u00e9mergence d\u2019un juteux business en ligne, la crainte que ces op\u00e9rateurs l\u2019entrave se fait jour. Les principaux fournisseurs en ligne (<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Yahoo!\" rel=\"noreferrer noopener\">Yahoo!<\/a>,&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" rel=\"noreferrer noopener\">Google<\/a>,&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Facebook\" rel=\"noreferrer noopener\">Facebook<\/a>, etc.) constituent d\u00e8s lors une seconde classe d\u2019ap\u00f4tres de la \u00abneutralit\u00e9 du net\u00bb. Leur lobby en sa faveur devient permanent \u00e0&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Washington_(district_de_Columbia)\" rel=\"noreferrer noopener\">Washington<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De fait, leurs int\u00e9r\u00eats s\u2019opposent directement \u00e0 ceux des op\u00e9rateurs. L\u00e0 o\u00f9 les seconds voudraient augmenter la tarification pour les plus gros \u00e9metteurs de donn\u00e9es, les premiers veulent limiter au maximum leurs frais pour transporter leurs donn\u00e9es entre eux et leurs consommateurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, suite \u00e0 la d\u00e9cision am\u00e9ricaine, une nouvelle cat\u00e9gorie de d\u00e9fenseurs de la \u00abneutralit\u00e9 du net\u00bb appara\u00eet : ceux qui s\u2019inqui\u00e8tent des cons\u00e9quences de ce nouveau&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/No_man%27s_land\" rel=\"noreferrer noopener\">no mans&rsquo; land<\/a>&nbsp;juridique. Cat\u00e9gorie avec laquelle je partage une certaine anxi\u00e9t\u00e9.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Quelles cons\u00e9quences suite \u00e0 la d\u00e9cision am\u00e9ricaine ?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, si je plaide pour une \u00e9volution du principe, c\u2019est toujours dans un cadre d\u2019une r\u00e9gulation d\u00e9mocratique et ind\u00e9pendante visant \u00e0 r\u00e9ellement transformer internet en un \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bien_commun\" target=\"_blank\" rel=\"noreferrer noopener\">bien commun<\/a>\u00bb&nbsp;[<a href=\"#5\">5<\/a>]. Or la nouvelle approche de la&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Federal_Communications_Commission\" target=\"_blank\" rel=\"noreferrer noopener\">FCC<\/a>&nbsp;appelle moins de r\u00e9gulation et non pas une \u00abmeilleure\u00bb r\u00e9gulation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ne d\u00e9finissant aucun cadre pr\u00e9cis quant \u00e0 la possibilit\u00e9 de discriminer techniquement et\/ou \u00e9conomiquement des datagrammes, et donc des acteurs en ligne, la&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Federal_Communications_Commission\" rel=\"noreferrer noopener\">FCC<\/a>&nbsp;semble ouvrir la porte \u00e0 des d\u00e9rives possibles. J\u2019en identifie deux types.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primo, l\u2019\u00e9mergence d\u2019un \u00abinternet de classe\u00bb. Jusqu\u2019ici, sur les autoroutes de l\u2019information, chaque datagramme emprunte n\u2019importe laquelle des \u00abbandes<sup data-fn=\"656b8f88-2467-4afe-8bc6-a2f290c18df1\" class=\"fn\"><a href=\"#656b8f88-2467-4afe-8bc6-a2f290c18df1\" id=\"656b8f88-2467-4afe-8bc6-a2f290c18df1-link\">8<\/a><\/sup>\u00bb disponibles suivant un principe de \u00ab<a href=\"https:\/\/fr.wikipedia.org\/wiki\/File_(structure_de_donn%C3%A9es)\" target=\"_blank\" rel=\"noreferrer noopener\">premier arriv\u00e9, premier servi<\/a>\u00bb. Demain, les plus riches pourraient se r\u00e9server les bandes les plus rapides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un avantage d\u2019abord pour les plus gros fournisseurs capables d\u2019investir plus pour le transport. D\u00e8s 2014, le fournisseur&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Netflix\" target=\"_blank\" rel=\"noreferrer noopener\">Netflix<\/a>&nbsp;cherchait un accord avec l\u2019op\u00e9rateur am\u00e9ricain&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Comcast\" target=\"_blank\" rel=\"noreferrer noopener\">Comcast<\/a>&nbsp;pour que ses datagrammes soient v\u00e9hicul\u00e9s en priorit\u00e9 sur la portion du r\u00e9seau g\u00e9r\u00e9e par ce dernier&nbsp;[<a href=\"#10\" rel=\"nofollow\">10<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais cela renforcerait aussi les fractures num\u00e9riques socio-\u00e9conomiques existantes en assurant aux internautes les plus ais\u00e9s un bien meilleur acc\u00e8s \u00e0 internet et \u00e0 ses services. Le tout dans un contexte o\u00f9 de plus en plus de t\u00e2ches essentielles se font en ligne (comme chercher un emploi).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce premier danger s\u2019inscrit (pour l\u2019essentiel) dans une discrimination des datagrammes bas\u00e9e sur les&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Adresse_IP\" rel=\"noreferrer noopener\">adresses IP<\/a>&nbsp;des \u00e9metteurs et\/ou sur celles des r\u00e9cepteurs. Un second risque possible serait de discriminer les datagrammes sur base des contenus v\u00e9hicul\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rateurs pourraient, \u00e9ventuellement pour le compte de tiers, mettre en place une censure \u00e0 grande \u00e9chelle. L\u2019exemple de la Chine nous rappelle que les technologies n\u00e9cessaires existent. Signalons au passage que nombre d\u2019entre elles sont fournies par des entreprises occidentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et les g\u00e9ants ne se g\u00eanent pas pour discriminer ou avantager des contenus. Prenons&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Google\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a><sup data-fn=\"4df7afc1-2439-4dd6-8c7e-2b010632d5cc\" class=\"fn\"><a href=\"#4df7afc1-2439-4dd6-8c7e-2b010632d5cc\" id=\"4df7afc1-2439-4dd6-8c7e-2b010632d5cc-link\">9<\/a><\/sup>. La&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Commission_europ%C3%A9enne\" target=\"_blank\" rel=\"noreferrer noopener\">Commission europ\u00e9enne<\/a>&nbsp;lui inflige en 2017 \u20ac 2,42 milliards d\u2019amende car il favorise son comparateur de prix&nbsp;[<a href=\"#11\" rel=\"nofollow\">11<\/a>]. On sait aussi qu\u2019entre 2006 et 2009, il p\u00e9nalise le site Web d\u2019un concurrent&nbsp;[<a href=\"#12\" rel=\"nofollow\">12<\/a>].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certes, le changement de position de la&nbsp;<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Federal_Communications_Commission\" rel=\"noreferrer noopener\">FCC<\/a>&nbsp;ne modifie \u00e9videmment pas le corpus l\u00e9gislatif existant. La libert\u00e9 d\u2019expression ou encore les lois antitrust restent en vigueur et les tribunaux pourront \u00eatre saisis en cas de fortes d\u00e9rives. Mais toute le monde pourra-t-il se payer de longs proc\u00e8s ?<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a>Remettre l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral au c\u0153ur d\u2019internet<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Il est beaucoup trop t\u00f4t pour \u00e9valuer les cons\u00e9quences pr\u00e9cises de l\u2019abandon am\u00e9ricain du principe de \u00abneutralit\u00e9 du net\u00bb. Les risques apparaissent bien r\u00e9els, mais le pire n\u2019est pas (encore) certain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parall\u00e8lement, de nombreux responsables politiques europ\u00e9ens s\u2019empressent de rappeler que ce principe reste scrupuleusement respect\u00e9 au sein de l\u2019<a target=\"_blank\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Union_europ%C3%A9enne\" rel=\"noreferrer noopener\">Union europ\u00e9enne<\/a>. Mais, comme je l\u2019ai indiqu\u00e9, ce n\u2019est sans doute pas non plus la meilleure option pour les citoyens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9alit\u00e9, on passe surtout \u00e0 c\u00f4t\u00e9 de l\u2019essentiel : quel internet voulons nous pour demain ? Internet \u00e9volue \u00e0 une vitesse telle que les \u00c9tats se retrouvent r\u00e9duits au r\u00f4le de simples spectateurs dans un monde d\u00e9sormais domin\u00e9 par les g\u00e9ants du num\u00e9rique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Or, quelques que soient les bonnes intentions affich\u00e9es par ces derniers, au bout du compte, ils poursuivent un objectif on ne peut plus \u00e9go\u00efste : assurer leur croissance et, le plus souvent, satisfaire leurs actionnaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je reste convaincu que, dans un \u00c9tat d\u00e9mocratique, la puissance publique reste la seule apte \u00e0 privil\u00e9gier l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral par rapport aux int\u00e9r\u00eats particuliers&nbsp;[<a href=\"#5\" rel=\"nofollow\">5<\/a>]. Encore faut-il que nos responsables politiques se donnent les moyens \u2013 moraux, financiers et l\u00e9gislatifs \u2013 pour s\u2019opposer au rouleau compresseur du capitalisme num\u00e9rique. Mais ceci est une autre histoire\u2026<a href=\"http:\/\/www.twitter.com\/pascalfrancq\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9f\u00e9rences<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"1\">[1]&nbsp;Pascal Francq,&nbsp;<em>Internet: Tome 1, La construction d\u2019un mythe<\/em>, \u00c9ditions Modulaires Europ\u00e9ennes, 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"2\">[2]&nbsp;Tim Wu, \u00abNetwork Neutrality, Broadband Discrimination\u00bb,&nbsp;<em>Journal of Telecommunications and High Technology Law<\/em>, 2, pp. 141\u2013178, 2003.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"3\">[3]&nbsp;Andrew Odlyzko, \u00abNetwork neutrality, search neutrality, and the never-ending conflict between efficiency and fairness in markets\u00bb,&nbsp;<em>Review of Network Economics<\/em>, 8(1), pp. 40\u201360, 2009.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"4\">[4]&nbsp;Batya Friedman&nbsp;&amp;&nbsp;Helen Nissenbaum, \u00abBias in Computer Systems\u00bb,&nbsp;<em>ACM Transactions on Information Systems<\/em>, 14(3), pp. 330\u201147, 1996.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"5\">[5]&nbsp;Pascal Francq,&nbsp;<em><a href=\"https:\/\/www.researchgate.net\/publication\/267289354_Neutrality_in_internet_regulation_three_regulatory_principles\" target=\"_blank\" rel=\"noreferrer noopener\">Neutrality in internet regulation: three regulatory principles<\/a><\/em>, essai technique, Paul Otlet Institute, 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"6\">[6]&nbsp;Lev Muchnik,&nbsp;Sinan Aral&nbsp;&amp;&nbsp;Sean J. Taylor, \u00abSocial Influence Bias: A Randomized Experiment\u00bb,&nbsp;<em>Science<\/em>, 341(6), pp. 647\u2013651, 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"7\">[7]&nbsp;Adam D. I. Kramer,&nbsp;Jamie E. Guillory&nbsp;&amp;&nbsp;Jeffrey T. Hancock, \u00abExperimental Evidence of Massive-Scale Emotional Contagion through Social Networks\u00bb,&nbsp;<em>Proceedings of the National Academy of Sciences<\/em>, 111(24), pp. 8788\u20138790, 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"8\">[8]&nbsp;Pascal Francq,&nbsp;<em>Internet: Tome 2, Le caract\u00e8re f\u00e9tiche<\/em>, \u00c9ditions Modulaires Europ\u00e9ennes, 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"9\">[9]&nbsp;John Perry Barlow,&nbsp;<em><a href=\"http:\/\/homes.eff.org\/~barlow\/Declaration-Final.html\" target=\"_blank\" rel=\"noreferrer noopener\">A Declaration of the Independence of Cyberspace<\/a><\/em>, 1996.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"10\">[10]&nbsp;Edward Wyatt&nbsp;&amp;&nbsp;Noam Cohen, \u00ab<a href=\"http:\/\/www.nytimes.com\/2014\/02\/24\/business\/media\/comcast-and-netflix-reach-a-streaming-agreement.html\" target=\"_blank\" rel=\"noreferrer noopener\">Comcast and Netflix Reach Deal on Service<\/a>\u00bb.&nbsp;<em>The New York Times<\/em>, 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"11\">[11]&nbsp;C\u00e9cile Ducourtieux, \u00ab<a href=\"file:\/\/\/Users\/pfrancq\/POI\/www\/opinions\/www.lemonde.fr\/economie\/article\/2017\/06\/27\/bruxelles-punit-google-d-une-amende-record_5151710_3234.html\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019Union europ\u00e9enne punit Google d\u2019une amende record de 2,42 milliards d\u2019euros<\/a>\u00bb,&nbsp;<em>Le Monde<\/em>, 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"12\">[12]&nbsp;James Grimmelmann, \u00abSome skepticism about search neutrality\u00bb, Dans&nbsp;<em>The Next Digital Decade: Essays on the Future of the Internet<\/em>,&nbsp;Berin Szoka&nbsp;&amp;&nbsp;Adam Marcus&nbsp;(\u00e9d.), pp. 435\u2013459, TechFreedom.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Notes<\/h5>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8\">Il y a bien eu quelques tentatives d\u2019entorses par les op\u00e9rateurs de t\u00e9l\u00e9communications, mais ces derni\u00e8res avaient toujours \u00e9t\u00e9 recadr\u00e9es (par la FCC ou par des nouveaux dispositifs l\u00e9gaux). <a href=\"#ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8-link\" aria-label=\"Aller \u00e0 la note de bas de page 1\">\u21a9\ufe0e<\/a><\/li><li id=\"c51f6dad-f36c-422d-9a8d-41474b2eff38\">Je me contenterai dans la suite de ce billet de les d\u00e9signer simplement par \u00ables op\u00e9rateurs\u00bb. <a href=\"#c51f6dad-f36c-422d-9a8d-41474b2eff38-link\" aria-label=\"Aller \u00e0 la note de bas de page 2\">\u21a9\ufe0e<\/a><\/li><li id=\"ae98b346-6197-4b58-9cfc-c665470e5fc7\">En laissant chaque datagramme suivre son propre chemin, on assure une flexibilit\u00e9 maximum du r\u00e9seau internet. En effet, en cas de congestion, les datagrammes peuvent emprunter des chemins moins encombr\u00e9s. Mais comme on ne garantit pas que les datagrammes arrivent dans l\u2019ordre de leur emission, il faut les r\u00e9ordonner \u00e0 l\u2019arriv\u00e9e (ce que se fait facilement en leur ajoutant un num\u00e9ro de s\u00e9quence lors de l\u2019envoi). <a href=\"#ae98b346-6197-4b58-9cfc-c665470e5fc7-link\" aria-label=\"Aller \u00e0 la note de bas de page 3\">\u21a9\ufe0e<\/a><\/li><li id=\"fa97db0f-27a0-49d2-9d74-9c3381c61df5\">Par exemple, lorsqu\u2019un utilisateur lit mon billet tout en \u00e9coutant de la musique en streaming, certains datagrammes contiendront des donn\u00e9es textuelles et picturales (images pr\u00e9sentes dans mon billet), d\u2019autres renfermeront des donn\u00e9es audio. <a href=\"#fa97db0f-27a0-49d2-9d74-9c3381c61df5-link\" aria-label=\"Aller \u00e0 la note de bas de page 4\">\u21a9\ufe0e<\/a><\/li><li id=\"ef33b27c-7592-430f-a00e-9f6d3ce50ae8\">Rappelons que tous les appareils connect\u00e9s \u00e0 internet sont des n\u0153uds. Ce sont d\u2019abord les appareils \u00aben bord de r\u00e9seau\u00bb (serveurs, ordinateurs personnels, smartphones, etc.), mais aussi les machines charg\u00e9es de l\u2019acheminement \u00abdans le r\u00e9seau\u00bb (routeurs, commutateurs, etc.). Pour acheminer un datagramme d\u2019un point \u00e0 un autre du r\u00e9seau, celui-ci est propag\u00e9 de n\u0153ud en n\u0153ud. <a href=\"#ef33b27c-7592-430f-a00e-9f6d3ce50ae8-link\" aria-label=\"Aller \u00e0 la note de bas de page 5\">\u21a9\ufe0e<\/a><\/li><li id=\"e004d03b-87cb-4ed8-b5bc-f3afa59c0c43\">En pratique, chaque n\u0153ud propage les datagrammes sur base d\u2019informations locales. Il estime notamment si les n\u0153uds \u00abproches\u00bb semblent ou non congestionn\u00e9s. En fonction de cela, il favorise la propagation vers des n\u0153uds en apparence non congestionn\u00e9s. Mais un n\u0153ud ne \u00abvoit\u00bb pas ce qui ce qui passe au-del\u00e0 de quelques n\u0153uds en aval de lui. <a href=\"#e004d03b-87cb-4ed8-b5bc-f3afa59c0c43-link\" aria-label=\"Aller \u00e0 la note de bas de page 6\">\u21a9\ufe0e<\/a><\/li><li id=\"90d69fc0-dc46-4b58-b598-11909f96d695\">En effet, apr\u00e8s en avoir financ\u00e9 le d\u00e9veloppement initial, les autorit\u00e9s am\u00e9ricaines d\u00e9cid\u00e8rent de se d\u00e9sengager de la gestion en laissant les initiatives priv\u00e9es prendre le relais. <a href=\"#90d69fc0-dc46-4b58-b598-11909f96d695-link\" aria-label=\"Aller \u00e0 la note de bas de page 7\">\u21a9\ufe0e<\/a><\/li><li id=\"656b8f88-2467-4afe-8bc6-a2f290c18df1\">En pratique, un c\u00e2ble optique, qui repr\u00e9sente une autoroute de l\u2019information, comprend plusieurs canaux qui correspondent aux bandes de nos routes d\u2019asphalte. <a href=\"#656b8f88-2467-4afe-8bc6-a2f290c18df1-link\" aria-label=\"Aller \u00e0 la note de bas de page 8\">\u21a9\ufe0e<\/a><\/li><li id=\"4df7afc1-2439-4dd6-8c7e-2b010632d5cc\">Google n\u2019est \u00e9videmment pas le seul g\u00e9ant \u00e0 effectuer de telles discriminations. Des exemples existent pour Apple, Facebook, LinkedIn, etc. <a href=\"#4df7afc1-2439-4dd6-8c7e-2b010632d5cc-link\" aria-label=\"Aller \u00e0 la note de bas de page 9\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Le 14 d\u00e9cembre dernier, la&nbsp;Federal Communications Commission (FCC), l\u2019agence f\u00e9d\u00e9rale am\u00e9ricaine charg\u00e9e de la r\u00e9gulation des t\u00e9l\u00e9communications,&nbsp;annonce la fin de ce que l&rsquo;on appelle la \u00ab neutralit\u00e9 du net \u00bb.&nbsp; Ce principe de fonctionnement d\u2019internet, en vigueur depuis ses d\u00e9buts, incarne aux yeux de beaucoup une notion d\u2019\u00e9galit\u00e9 cens\u00e9e \u00eatre inh\u00e9rente au r\u00e9seau : que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"[{\"content\":\"Il y a bien eu quelques tentatives d\u2019entorses par les op\u00e9rateurs de t\u00e9l\u00e9communications, mais ces derni\u00e8res avaient toujours \u00e9t\u00e9 recadr\u00e9es (par la FCC ou par des nouveaux dispositifs l\u00e9gaux).\",\"id\":\"ae19ddf1-b0ee-4a0f-8fbe-0fcaa63159c8\"},{\"content\":\"Je me contenterai dans la suite de ce billet de les d\u00e9signer simplement par \u00ables op\u00e9rateurs\u00bb.\",\"id\":\"c51f6dad-f36c-422d-9a8d-41474b2eff38\"},{\"content\":\"En laissant chaque datagramme suivre son propre chemin, on assure une flexibilit\u00e9 maximum du r\u00e9seau internet. En effet, en cas de congestion, les datagrammes peuvent emprunter des chemins moins encombr\u00e9s. Mais comme on ne garantit pas que les datagrammes arrivent dans l\u2019ordre de leur emission, il faut les r\u00e9ordonner \u00e0 l\u2019arriv\u00e9e (ce que se fait facilement en leur ajoutant un num\u00e9ro de s\u00e9quence lors de l\u2019envoi).\",\"id\":\"ae98b346-6197-4b58-9cfc-c665470e5fc7\"},{\"content\":\"Par exemple, lorsqu\u2019un utilisateur lit mon billet tout en \u00e9coutant de la musique en streaming, certains datagrammes contiendront des donn\u00e9es textuelles et picturales (images pr\u00e9sentes dans mon billet), d\u2019autres renfermeront des donn\u00e9es audio.\",\"id\":\"fa97db0f-27a0-49d2-9d74-9c3381c61df5\"},{\"content\":\"Rappelons que tous les appareils connect\u00e9s \u00e0 internet sont des n\u0153uds. Ce sont d\u2019abord les appareils \u00aben bord de r\u00e9seau\u00bb (serveurs, ordinateurs personnels, smartphones, etc.), mais aussi les machines charg\u00e9es de l\u2019acheminement \u00abdans le r\u00e9seau\u00bb (routeurs, commutateurs, etc.). Pour acheminer un datagramme d\u2019un point \u00e0 un autre du r\u00e9seau, celui-ci est propag\u00e9 de n\u0153ud en n\u0153ud.\",\"id\":\"ef33b27c-7592-430f-a00e-9f6d3ce50ae8\"},{\"content\":\"En pratique, chaque n\u0153ud propage les datagrammes sur base d\u2019informations locales. Il estime notamment si les n\u0153uds \u00abproches\u00bb semblent ou non congestionn\u00e9s. En fonction de cela, il favorise la propagation vers des n\u0153uds en apparence non congestionn\u00e9s. Mais un n\u0153ud ne \u00abvoit\u00bb pas ce qui ce qui passe au-del\u00e0 de quelques n\u0153uds en aval de lui.\",\"id\":\"e004d03b-87cb-4ed8-b5bc-f3afa59c0c43\"},{\"content\":\"En effet, apr\u00e8s en avoir financ\u00e9 le d\u00e9veloppement initial, les autorit\u00e9s am\u00e9ricaines d\u00e9cid\u00e8rent de se d\u00e9sengager de la gestion en laissant les initiatives priv\u00e9es prendre le relais.\",\"id\":\"90d69fc0-dc46-4b58-b598-11909f96d695\"},{\"content\":\"En pratique, un c\u00e2ble optique, qui repr\u00e9sente une autoroute de l\u2019information, comprend plusieurs canaux qui correspondent aux bandes de nos routes d\u2019asphalte.\",\"id\":\"656b8f88-2467-4afe-8bc6-a2f290c18df1\"},{\"content\":\"Google n\u2019est \u00e9videmment pas le seul g\u00e9ant \u00e0 effectuer de telles discriminations. Des exemples existent pour Apple, Facebook, LinkedIn, etc.\",\"id\":\"4df7afc1-2439-4dd6-8c7e-2b010632d5cc\"}]"},"categories":[100],"tags":[15,98],"class_list":["post-1611","post","type-post","status-publish","format-standard","hentry","category-politic","tag-architecture","tag-politic"],"views":37,"_links":{"self":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/comments?post=1611"}],"version-history":[{"count":7,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/1611\/revisions"}],"predecessor-version":[{"id":2817,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/posts\/1611\/revisions\/2817"}],"wp:attachment":[{"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/categories?post=1611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.francq.info\/index.php\/wp-json\/wp\/v2\/tags?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}